{"id":1158,"date":"2023-05-15T10:34:38","date_gmt":"2023-05-15T08:34:38","guid":{"rendered":"https:\/\/blog.rwth-aachen.de\/itc-changes\/?p=1158"},"modified":"2025-11-18T10:35:28","modified_gmt":"2025-11-18T09:35:28","slug":"abschaltung-der-cas-campus-exporte","status":"publish","type":"post","link":"https:\/\/blog.rwth-aachen.de\/itc-changes\/2023\/05\/15\/abschaltung-der-cas-campus-exporte\/","title":{"rendered":"Abschaltung der CAS Campus Exporte"},"content":{"rendered":"<p>Abschaltung der CAS Campus Exporte und Umstellung auf RWTHcontacts Exporte.<\/p>\n<p>Weitere Informationen finden Sie im <a class=\"external-link\" href=\"https:\/\/blog.rwth-aachen.de\/itc\/2023\/05\/08\/rwthcontacts-export\/\" target=\"_blank\" rel=\"external noopener\" data-pcs-link-token=\"sabio_link_ref_6_\">IT Center Blog<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Abschaltung der CAS Campus Exporte und Umstellung auf RWTHcontacts Exporte. Weitere Informationen finden Sie im IT Center Blog.<\/p>\n","protected":false},"author":6912,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"c2c_always_allow_admin_comments":false,"footnotes":""},"categories":[32],"tags":[],"class_list":["post-1158","post","type-post","status-publish","format-standard","hentry","category-rwthcontacts"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.8 - aioseo.com -->\n\t<meta name=\"description\" content=\"Abschaltung der CAS Campus Exporte und Umstellung auf RWTHcontacts Exporte. Weitere Informationen finden Sie im IT Center Blog.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Bogdan Noskov\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/blog.rwth-aachen.de\/itc-changes\/2023\/05\/15\/abschaltung-der-cas-campus-exporte\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.8\" \/>\n\t\t<meta property=\"og:locale\" content=\"de_DE\" \/>\n\t\t<meta property=\"og:site_name\" content=\"IT Center Changes - Change Logs des IT Centers\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Abschaltung der CAS Campus Exporte - IT Center Changes\" \/>\n\t\t<meta property=\"og:description\" content=\"Abschaltung der CAS Campus Exporte und Umstellung auf RWTHcontacts Exporte. Weitere Informationen finden Sie im IT Center Blog.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/blog.rwth-aachen.de\/itc-changes\/2023\/05\/15\/abschaltung-der-cas-campus-exporte\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-05-15T08:34:38+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-11-18T09:35:28+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Abschaltung der CAS Campus Exporte - IT Center Changes\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Abschaltung der CAS Campus Exporte und Umstellung auf RWTHcontacts Exporte. Weitere Informationen finden Sie im IT Center Blog.\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc-changes\\\/2023\\\/05\\\/15\\\/abschaltung-der-cas-campus-exporte\\\/#blogposting\",\"name\":\"Abschaltung der CAS Campus Exporte - IT Center Changes\",\"headline\":\"Abschaltung der CAS Campus Exporte\",\"author\":{\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc-changes\\\/author\\\/6912\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc-changes\\\/#organization\"},\"datePublished\":\"2023-05-15T10:34:38+02:00\",\"dateModified\":\"2025-11-18T10:35:28+01:00\",\"inLanguage\":\"de-DE\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc-changes\\\/2023\\\/05\\\/15\\\/abschaltung-der-cas-campus-exporte\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc-changes\\\/2023\\\/05\\\/15\\\/abschaltung-der-cas-campus-exporte\\\/#webpage\"},\"articleSection\":\"RWTHcontacts\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc-changes\\\/2023\\\/05\\\/15\\\/abschaltung-der-cas-campus-exporte\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc-changes#listItem\",\"position\":1,\"name\":\"Zu Hause\",\"item\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc-changes\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc-changes\\\/category\\\/rwthcontacts\\\/#listItem\",\"name\":\"RWTHcontacts\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc-changes\\\/category\\\/rwthcontacts\\\/#listItem\",\"position\":2,\"name\":\"RWTHcontacts\",\"item\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc-changes\\\/category\\\/rwthcontacts\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc-changes\\\/2023\\\/05\\\/15\\\/abschaltung-der-cas-campus-exporte\\\/#listItem\",\"name\":\"Abschaltung der CAS Campus Exporte\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc-changes#listItem\",\"name\":\"Zu Hause\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc-changes\\\/2023\\\/05\\\/15\\\/abschaltung-der-cas-campus-exporte\\\/#listItem\",\"position\":3,\"name\":\"Abschaltung der CAS Campus Exporte\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc-changes\\\/category\\\/rwthcontacts\\\/#listItem\",\"name\":\"RWTHcontacts\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc-changes\\\/#organization\",\"name\":\"IT Center Changes\",\"description\":\"Change Logs des IT Centers\",\"url\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc-changes\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc-changes\\\/author\\\/6912\\\/#author\",\"url\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc-changes\\\/author\\\/6912\\\/\",\"name\":\"Bogdan Noskov\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc-changes\\\/2023\\\/05\\\/15\\\/abschaltung-der-cas-campus-exporte\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/49db38845aaf44346515aa4157c266b0724c921351b52b9bcb867c199959a3c4?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Bogdan Noskov\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc-changes\\\/2023\\\/05\\\/15\\\/abschaltung-der-cas-campus-exporte\\\/#webpage\",\"url\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc-changes\\\/2023\\\/05\\\/15\\\/abschaltung-der-cas-campus-exporte\\\/\",\"name\":\"Abschaltung der CAS Campus Exporte - IT Center Changes\",\"description\":\"Abschaltung der CAS Campus Exporte und Umstellung auf RWTHcontacts Exporte. Weitere Informationen finden Sie im IT Center Blog.\",\"inLanguage\":\"de-DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc-changes\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc-changes\\\/2023\\\/05\\\/15\\\/abschaltung-der-cas-campus-exporte\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc-changes\\\/author\\\/6912\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc-changes\\\/author\\\/6912\\\/#author\"},\"datePublished\":\"2023-05-15T10:34:38+02:00\",\"dateModified\":\"2025-11-18T10:35:28+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc-changes\\\/#website\",\"url\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc-changes\\\/\",\"name\":\"IT Center Changes\",\"description\":\"Change Logs des IT Centers\",\"inLanguage\":\"de-DE\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc-changes\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Abschaltung der CAS Campus Exporte - IT Center Changes","description":"Abschaltung der CAS Campus Exporte und Umstellung auf RWTHcontacts Exporte. Weitere Informationen finden Sie im IT Center Blog.","canonical_url":"https:\/\/blog.rwth-aachen.de\/itc-changes\/2023\/05\/15\/abschaltung-der-cas-campus-exporte\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/blog.rwth-aachen.de\/itc-changes\/2023\/05\/15\/abschaltung-der-cas-campus-exporte\/#blogposting","name":"Abschaltung der CAS Campus Exporte - IT Center Changes","headline":"Abschaltung der CAS Campus Exporte","author":{"@id":"https:\/\/blog.rwth-aachen.de\/itc-changes\/author\/6912\/#author"},"publisher":{"@id":"https:\/\/blog.rwth-aachen.de\/itc-changes\/#organization"},"datePublished":"2023-05-15T10:34:38+02:00","dateModified":"2025-11-18T10:35:28+01:00","inLanguage":"de-DE","mainEntityOfPage":{"@id":"https:\/\/blog.rwth-aachen.de\/itc-changes\/2023\/05\/15\/abschaltung-der-cas-campus-exporte\/#webpage"},"isPartOf":{"@id":"https:\/\/blog.rwth-aachen.de\/itc-changes\/2023\/05\/15\/abschaltung-der-cas-campus-exporte\/#webpage"},"articleSection":"RWTHcontacts"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.rwth-aachen.de\/itc-changes\/2023\/05\/15\/abschaltung-der-cas-campus-exporte\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/blog.rwth-aachen.de\/itc-changes#listItem","position":1,"name":"Zu Hause","item":"https:\/\/blog.rwth-aachen.de\/itc-changes","nextItem":{"@type":"ListItem","@id":"https:\/\/blog.rwth-aachen.de\/itc-changes\/category\/rwthcontacts\/#listItem","name":"RWTHcontacts"}},{"@type":"ListItem","@id":"https:\/\/blog.rwth-aachen.de\/itc-changes\/category\/rwthcontacts\/#listItem","position":2,"name":"RWTHcontacts","item":"https:\/\/blog.rwth-aachen.de\/itc-changes\/category\/rwthcontacts\/","nextItem":{"@type":"ListItem","@id":"https:\/\/blog.rwth-aachen.de\/itc-changes\/2023\/05\/15\/abschaltung-der-cas-campus-exporte\/#listItem","name":"Abschaltung der CAS Campus Exporte"},"previousItem":{"@type":"ListItem","@id":"https:\/\/blog.rwth-aachen.de\/itc-changes#listItem","name":"Zu Hause"}},{"@type":"ListItem","@id":"https:\/\/blog.rwth-aachen.de\/itc-changes\/2023\/05\/15\/abschaltung-der-cas-campus-exporte\/#listItem","position":3,"name":"Abschaltung der CAS Campus Exporte","previousItem":{"@type":"ListItem","@id":"https:\/\/blog.rwth-aachen.de\/itc-changes\/category\/rwthcontacts\/#listItem","name":"RWTHcontacts"}}]},{"@type":"Organization","@id":"https:\/\/blog.rwth-aachen.de\/itc-changes\/#organization","name":"IT Center Changes","description":"Change Logs des IT Centers","url":"https:\/\/blog.rwth-aachen.de\/itc-changes\/"},{"@type":"Person","@id":"https:\/\/blog.rwth-aachen.de\/itc-changes\/author\/6912\/#author","url":"https:\/\/blog.rwth-aachen.de\/itc-changes\/author\/6912\/","name":"Bogdan Noskov","image":{"@type":"ImageObject","@id":"https:\/\/blog.rwth-aachen.de\/itc-changes\/2023\/05\/15\/abschaltung-der-cas-campus-exporte\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/49db38845aaf44346515aa4157c266b0724c921351b52b9bcb867c199959a3c4?s=96&d=mm&r=g","width":96,"height":96,"caption":"Bogdan Noskov"}},{"@type":"WebPage","@id":"https:\/\/blog.rwth-aachen.de\/itc-changes\/2023\/05\/15\/abschaltung-der-cas-campus-exporte\/#webpage","url":"https:\/\/blog.rwth-aachen.de\/itc-changes\/2023\/05\/15\/abschaltung-der-cas-campus-exporte\/","name":"Abschaltung der CAS Campus Exporte - IT Center Changes","description":"Abschaltung der CAS Campus Exporte und Umstellung auf RWTHcontacts Exporte. Weitere Informationen finden Sie im IT Center Blog.","inLanguage":"de-DE","isPartOf":{"@id":"https:\/\/blog.rwth-aachen.de\/itc-changes\/#website"},"breadcrumb":{"@id":"https:\/\/blog.rwth-aachen.de\/itc-changes\/2023\/05\/15\/abschaltung-der-cas-campus-exporte\/#breadcrumblist"},"author":{"@id":"https:\/\/blog.rwth-aachen.de\/itc-changes\/author\/6912\/#author"},"creator":{"@id":"https:\/\/blog.rwth-aachen.de\/itc-changes\/author\/6912\/#author"},"datePublished":"2023-05-15T10:34:38+02:00","dateModified":"2025-11-18T10:35:28+01:00"},{"@type":"WebSite","@id":"https:\/\/blog.rwth-aachen.de\/itc-changes\/#website","url":"https:\/\/blog.rwth-aachen.de\/itc-changes\/","name":"IT Center Changes","description":"Change Logs des IT Centers","inLanguage":"de-DE","publisher":{"@id":"https:\/\/blog.rwth-aachen.de\/itc-changes\/#organization"}}]},"og:locale":"de_DE","og:site_name":"IT Center Changes - Change Logs des IT Centers","og:type":"article","og:title":"Abschaltung der CAS Campus Exporte - IT Center Changes","og:description":"Abschaltung der CAS Campus Exporte und Umstellung auf RWTHcontacts Exporte. Weitere Informationen finden Sie im IT Center Blog.","og:url":"https:\/\/blog.rwth-aachen.de\/itc-changes\/2023\/05\/15\/abschaltung-der-cas-campus-exporte\/","article:published_time":"2023-05-15T08:34:38+00:00","article:modified_time":"2025-11-18T09:35:28+00:00","twitter:card":"summary_large_image","twitter:title":"Abschaltung der CAS Campus Exporte - IT Center Changes","twitter:description":"Abschaltung der CAS Campus Exporte und Umstellung auf RWTHcontacts Exporte. Weitere Informationen finden Sie im IT Center Blog."},"aioseo_meta_data":{"post_id":"1158","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2025-11-18 09:35:28","updated":"2025-11-18 09:35:28","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/blog.rwth-aachen.de\/itc-changes\" title=\"Zu Hause\">Zu Hause<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/blog.rwth-aachen.de\/itc-changes\/category\/rwthcontacts\/\" title=\"RWTHcontacts\">RWTHcontacts<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tAbschaltung der CAS Campus Exporte\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Zu Hause","link":"https:\/\/blog.rwth-aachen.de\/itc-changes"},{"label":"RWTHcontacts","link":"https:\/\/blog.rwth-aachen.de\/itc-changes\/category\/rwthcontacts\/"},{"label":"Abschaltung der CAS Campus Exporte","link":"https:\/\/blog.rwth-aachen.de\/itc-changes\/2023\/05\/15\/abschaltung-der-cas-campus-exporte\/"}],"_links":{"self":[{"href":"https:\/\/blog.rwth-aachen.de\/itc-changes\/wp-json\/wp\/v2\/posts\/1158","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.rwth-aachen.de\/itc-changes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.rwth-aachen.de\/itc-changes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.rwth-aachen.de\/itc-changes\/wp-json\/wp\/v2\/users\/6912"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.rwth-aachen.de\/itc-changes\/wp-json\/wp\/v2\/comments?post=1158"}],"version-history":[{"count":1,"href":"https:\/\/blog.rwth-aachen.de\/itc-changes\/wp-json\/wp\/v2\/posts\/1158\/revisions"}],"predecessor-version":[{"id":1159,"href":"https:\/\/blog.rwth-aachen.de\/itc-changes\/wp-json\/wp\/v2\/posts\/1158\/revisions\/1159"}],"wp:attachment":[{"href":"https:\/\/blog.rwth-aachen.de\/itc-changes\/wp-json\/wp\/v2\/media?parent=1158"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.rwth-aachen.de\/itc-changes\/wp-json\/wp\/v2\/categories?post=1158"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.rwth-aachen.de\/itc-changes\/wp-json\/wp\/v2\/tags?post=1158"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}