{"id":5568,"date":"2019-04-26T13:00:29","date_gmt":"2019-04-26T11:00:29","guid":{"rendered":"https:\/\/blog.rwth-aachen.de\/itc\/?p=5568"},"modified":"2025-02-24T11:24:42","modified_gmt":"2025-02-24T10:24:42","slug":"78-000","status":"publish","type":"post","link":"https:\/\/blog.rwth-aachen.de\/itc\/en\/2019\/04\/26\/78-000\/","title":{"rendered":"78.000"},"content":{"rendered":"<div class=\"twoclick_social_bookmarks_post_5568 social_share_privacy clearfix 1.6.4 locale-en_US sprite-en_US\"><\/div><div class=\"twoclick-js\"><script type=\"text\/javascript\">\/* <![CDATA[ *\/\njQuery(document).ready(function($){if($('.twoclick_social_bookmarks_post_5568')){$('.twoclick_social_bookmarks_post_5568').socialSharePrivacy({\"txt_help\":\"Wenn Sie diese Felder durch einen Klick aktivieren, werden Informationen an Facebook, Twitter, Flattr, Xing, t3n, LinkedIn, Pinterest oder Google eventuell ins Ausland \\u00fcbertragen und unter Umst\\u00e4nden auch dort gespeichert. N\\u00e4heres erfahren Sie durch einen Klick auf das <em>i<\\\/em>.\",\"settings_perma\":\"Dauerhaft aktivieren und Daten\\u00fcber-tragung zustimmen:\",\"info_link\":\"http:\\\/\\\/www.heise.de\\\/ct\\\/artikel\\\/2-Klicks-fuer-mehr-Datenschutz-1333879.html\",\"uri\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/en\\\/2019\\\/04\\\/26\\\/78-000\\\/\",\"post_id\":5568,\"post_title_referrer_track\":\"78.000\",\"display_infobox\":\"on\"});}});\n\/* ]]> *\/<\/script><\/div><p>&nbsp;<\/p>\r\n\r\n<div class=\"wp-block-image\">\r\n<figure class=\"alignleft\">\r\n<div id=\"attachment_5386\" style=\"width: 170px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-5386\" class=\"wp-image-5386\" src=\"https:\/\/blog.rwth-aachen.de\/itc\/files\/2019\/04\/itc_blogserie_1_HSG-Kopie_160-1-3.png\" alt=\"\" width=\"160\" height=\"160\" srcset=\"https:\/\/blog.rwth-aachen.de\/itc\/files\/2019\/04\/itc_blogserie_1_HSG-Kopie_160-1-3.png 160w, https:\/\/blog.rwth-aachen.de\/itc\/files\/2019\/04\/itc_blogserie_1_HSG-Kopie_160-1-3-150x150.png 150w, https:\/\/blog.rwth-aachen.de\/itc\/files\/2019\/04\/itc_blogserie_1_HSG-Kopie_160-1-3-50x50.png 50w\" sizes=\"auto, (max-width: 160px) 100vw, 160px\" \/><p id=\"caption-attachment-5386\" class=\"wp-caption-text\">Quelle: Eigene Darstellung<\/p><\/div>\r\n<\/figure>\r\n<\/div>\r\n\r\n<p>&nbsp;<\/p>\r\n\r\n<p class=\"wp-block-paragraph\">Das <a href=\"https:\/\/help.itc.rwth-aachen.de\/service\/t4ctl3msqrmt\/article\/0c39665e06364621bd17be42d1890a06\/\">Backup-Portal\u202f<\/a>bietet\u202feine sichere und verl\u00e4ssliche\u202fM\u00f6glichkeit Server in den Instituten auf den Backup-Servern im IT Center\u202fversioniert\u202fzu sichern und bei Bedarf wiederherzustellen.\u202f<\/p>\r\n\r\n<p>&nbsp;<\/p>\r\n\r\n<p class=\"wp-block-paragraph\">Es stellt\u202fdabei\u202fsicher, dass es zu keinem Verlust wissenschaftlicher Daten kommt aufgrund von Defekten an Rechnern und f\u00fcr eine schnelle und sichere Wiederherstellung der Daten gesorgt ist.\u202f\u202f<\/p>\r\n\r\n<p>&nbsp;<\/p>\r\n\r\n<p class=\"wp-block-paragraph\">Allein im Januar 2019\u202fkonnte\u202ff\u00fcr alle Fakult\u00e4ten und zentralen Einrichtungen der RWTH\u202fAachen eine\u202funglaublich hohe Menge an Daten gespeichert werden \u2013\u202fbis zu\u202f78.000\u202fGigabyte\u202ft\u00e4glich!\u202f<\/p>\r\n\r\n<p>&nbsp;<\/p>\r\n\r\n<p class=\"wp-block-paragraph\">Um die Daten eines Rechners auf einem Bandarchiv sichern zu\u202fk\u00f6nnen, wird\u202feine Client-Software installiert (Spectrum Protect Client), die periodisch und automatisiert die \u00dcbertragung der Daten durchf\u00fchrt.\u202fDer Betrieb l\u00e4uft bereits seit 1998 und zeigt, dass mit nur geringem Aufwand\u202fDatenmengen gespeichert und wiederhergestellt werden k\u00f6nnen.\u202f<\/p>\r\n\r\n<p>&nbsp;<\/p>\r\n\r\n<p><!--more--><\/p>\r\n\r\n<p>&nbsp;<\/p>\r\n\r\n<p class=\"wp-block-paragraph\">F\u00fcr die langfristige Aufbewahrung wissenschaftlicher Daten kann der, ebenfalls \u00fcber das Backup-Portal zug\u00e4ngliche, Archiv-Dienst von Instituten verwendet werden.<\/p>\r\n\r\n<p>&nbsp;<\/p>\r\n\r\n<p class=\"wp-block-paragraph\">Die Anmeldung im Backup-System erfolgt \u00fcber\u202fbackup.itc.rwth-aachen.de\u202fund erfordert die Eingabe Ihre\u202fZugangsdaten f\u00fcr den\u202f<a href=\"https:\/\/sso.rwth-aachen.de\/idp\/profile\/SAML2\/Redirect\/SSO?execution=e2s1&amp;lang=en\">RWTH Single Sign-On<\/a>.\u202f\u00a0<\/p>\r\n\r\n<p>&nbsp;<\/p>\r\n\r\n<p class=\"wp-block-paragraph\">Weitere Informationen zum Dienst Backup finden Sie auf <a href=\"https:\/\/help.itc.rwth-aachen.de\/service\/t4ctl3msqrmt\/\">IT Center Help<\/a>.\u00a0<\/p>\r\n\r\n<p>&nbsp;<\/p>\r\n\r\n<p class=\"wp-block-paragraph\">Verantwortlich f\u00fcr die Inhalte des Beitrages sind Jonas Jansen und <a href=\"https:\/\/www.itc.rwth-aachen.de\/go\/id\/epvp\/gguid\/0x3CFCED905704E14FA6E77F1CFA159EC3\/allou\/1\/\">Sara Kaya.\u202f<\/a>\u00a0<\/p>\r\n\r\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Sorry, this entry is only available in Deutsch.<\/p>\n","protected":false},"author":1328,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"c2c_always_allow_admin_comments":false,"footnotes":""},"categories":[311],"tags":[],"class_list":["post-5568","post","type-post","status-publish","format-standard","hentry","category-fun-facts"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.8 - aioseo.com -->\n\t<meta name=\"description\" content=\"Das Backup-Portal bietet eine sichere und verl\u00e4ssliche M\u00f6glichkeit Server in den Instituten auf den Backup-Servern im IT Center versioniert zu sichern und bei Bedarf wiederherzustellen. Es stellt dabei sicher, dass es zu keinem Verlust wissenschaftlicher Daten kommt aufgrund von Defekten an Rechnern und f\u00fcr eine schnelle und sichere Wiederherstellung der Daten gesorgt ist. Allein im Januar 2019 konnte f\u00fcr alle\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Sara Kaya\"\/>\n\t<meta name=\"keywords\" content=\"fun &amp; facts\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/blog.rwth-aachen.de\/itc\/en\/2019\/04\/26\/78-000\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.8\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"IT Center Blog \u2022\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"78.000 \u2022 IT Center Blog\" \/>\n\t\t<meta property=\"og:description\" content=\"Das Backup-Portal bietet eine sichere und verl\u00e4ssliche M\u00f6glichkeit Server in den Instituten auf den Backup-Servern im IT Center versioniert zu sichern und bei Bedarf wiederherzustellen. Es stellt dabei sicher, dass es zu keinem Verlust wissenschaftlicher Daten kommt aufgrund von Defekten an Rechnern und f\u00fcr eine schnelle und sichere Wiederherstellung der Daten gesorgt ist. Allein im Januar 2019 konnte f\u00fcr alle\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/blog.rwth-aachen.de\/itc\/en\/2019\/04\/26\/78-000\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2019-04-26T11:00:29+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-02-24T10:24:42+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/itcenterrwth\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@ITCenterRWTH\" \/>\n\t\t<meta name=\"twitter:title\" content=\"78.000 \u2022 IT Center Blog\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Das Backup-Portal bietet eine sichere und verl\u00e4ssliche M\u00f6glichkeit Server in den Instituten auf den Backup-Servern im IT Center versioniert zu sichern und bei Bedarf wiederherzustellen. Es stellt dabei sicher, dass es zu keinem Verlust wissenschaftlicher Daten kommt aufgrund von Defekten an Rechnern und f\u00fcr eine schnelle und sichere Wiederherstellung der Daten gesorgt ist. Allein im Januar 2019 konnte f\u00fcr alle\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@ITCenterRWTH\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/en\\\/2019\\\/04\\\/26\\\/78-000\\\/#blogposting\",\"name\":\"78.000 \\u2022 IT Center Blog\",\"headline\":\"78.000\",\"author\":{\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/en\\\/author\\\/1328\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/en\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/files\\\/2019\\\/04\\\/itc_blogserie_1_HSG-Kopie_160-1-3.png\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/en\\\/2019\\\/04\\\/26\\\/78-000\\\/#articleImage\",\"width\":160,\"height\":160},\"datePublished\":\"2019-04-26T13:00:29+02:00\",\"dateModified\":\"2025-02-24T11:24:42+01:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/en\\\/2019\\\/04\\\/26\\\/78-000\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/en\\\/2019\\\/04\\\/26\\\/78-000\\\/#webpage\"},\"articleSection\":\"Fun &amp; Facts\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/en\\\/2019\\\/04\\\/26\\\/78-000\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/en\\\/category\\\/themen\\\/#listItem\",\"name\":\"Topic\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/en\\\/category\\\/themen\\\/#listItem\",\"position\":2,\"name\":\"Topic\",\"item\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/en\\\/category\\\/themen\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/en\\\/category\\\/themen\\\/fun-facts\\\/#listItem\",\"name\":\"Fun &amp; Facts\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/en\\\/category\\\/themen\\\/fun-facts\\\/#listItem\",\"position\":3,\"name\":\"Fun &amp; Facts\",\"item\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/en\\\/category\\\/themen\\\/fun-facts\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/en\\\/2019\\\/04\\\/26\\\/78-000\\\/#listItem\",\"name\":\"78.000\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/en\\\/category\\\/themen\\\/#listItem\",\"name\":\"Topic\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/en\\\/2019\\\/04\\\/26\\\/78-000\\\/#listItem\",\"position\":4,\"name\":\"78.000\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/en\\\/category\\\/themen\\\/fun-facts\\\/#listItem\",\"name\":\"Fun &amp; Facts\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/en\\\/#organization\",\"name\":\"IT Center RWTH Aachen University\",\"url\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/files\\\/2018\\\/09\\\/IT-Center-Logo.png\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/en\\\/2019\\\/04\\\/26\\\/78-000\\\/#organizationLogo\",\"width\":1312,\"height\":378,\"caption\":\"IT Center Logo\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/en\\\/2019\\\/04\\\/26\\\/78-000\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/itcenterrwth\",\"https:\\\/\\\/twitter.com\\\/ITCenterRWTH\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/itcenterrwthaachen\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/itcenterrwth\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/en\\\/author\\\/1328\\\/#author\",\"url\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/en\\\/author\\\/1328\\\/\",\"name\":\"Sara Kaya\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/en\\\/2019\\\/04\\\/26\\\/78-000\\\/#webpage\",\"url\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/en\\\/2019\\\/04\\\/26\\\/78-000\\\/\",\"name\":\"78.000 \\u2022 IT Center Blog\",\"description\":\"Das Backup-Portal bietet eine sichere und verl\\u00e4ssliche M\\u00f6glichkeit Server in den Instituten auf den Backup-Servern im IT Center versioniert zu sichern und bei Bedarf wiederherzustellen. Es stellt dabei sicher, dass es zu keinem Verlust wissenschaftlicher Daten kommt aufgrund von Defekten an Rechnern und f\\u00fcr eine schnelle und sichere Wiederherstellung der Daten gesorgt ist. Allein im Januar 2019 konnte f\\u00fcr alle\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/en\\\/2019\\\/04\\\/26\\\/78-000\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/en\\\/author\\\/1328\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/en\\\/author\\\/1328\\\/#author\"},\"datePublished\":\"2019-04-26T13:00:29+02:00\",\"dateModified\":\"2025-02-24T11:24:42+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/en\\\/\",\"name\":\"IT Center Blog\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"78.000 \u2022 IT Center Blog","description":"Das Backup-Portal bietet eine sichere und verl\u00e4ssliche M\u00f6glichkeit Server in den Instituten auf den Backup-Servern im IT Center versioniert zu sichern und bei Bedarf wiederherzustellen. Es stellt dabei sicher, dass es zu keinem Verlust wissenschaftlicher Daten kommt aufgrund von Defekten an Rechnern und f\u00fcr eine schnelle und sichere Wiederherstellung der Daten gesorgt ist. Allein im Januar 2019 konnte f\u00fcr alle","canonical_url":"https:\/\/blog.rwth-aachen.de\/itc\/en\/2019\/04\/26\/78-000\/","robots":"max-image-preview:large","keywords":"fun &amp; facts","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/blog.rwth-aachen.de\/itc\/en\/2019\/04\/26\/78-000\/#blogposting","name":"78.000 \u2022 IT Center Blog","headline":"78.000","author":{"@id":"https:\/\/blog.rwth-aachen.de\/itc\/en\/author\/1328\/#author"},"publisher":{"@id":"https:\/\/blog.rwth-aachen.de\/itc\/en\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/blog.rwth-aachen.de\/itc\/files\/2019\/04\/itc_blogserie_1_HSG-Kopie_160-1-3.png","@id":"https:\/\/blog.rwth-aachen.de\/itc\/en\/2019\/04\/26\/78-000\/#articleImage","width":160,"height":160},"datePublished":"2019-04-26T13:00:29+02:00","dateModified":"2025-02-24T11:24:42+01:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/blog.rwth-aachen.de\/itc\/en\/2019\/04\/26\/78-000\/#webpage"},"isPartOf":{"@id":"https:\/\/blog.rwth-aachen.de\/itc\/en\/2019\/04\/26\/78-000\/#webpage"},"articleSection":"Fun &amp; Facts"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.rwth-aachen.de\/itc\/en\/2019\/04\/26\/78-000\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/blog.rwth-aachen.de\/itc\/en#listItem","position":1,"name":"Home","item":"https:\/\/blog.rwth-aachen.de\/itc\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/blog.rwth-aachen.de\/itc\/en\/category\/themen\/#listItem","name":"Topic"}},{"@type":"ListItem","@id":"https:\/\/blog.rwth-aachen.de\/itc\/en\/category\/themen\/#listItem","position":2,"name":"Topic","item":"https:\/\/blog.rwth-aachen.de\/itc\/en\/category\/themen\/","nextItem":{"@type":"ListItem","@id":"https:\/\/blog.rwth-aachen.de\/itc\/en\/category\/themen\/fun-facts\/#listItem","name":"Fun &amp; Facts"},"previousItem":{"@type":"ListItem","@id":"https:\/\/blog.rwth-aachen.de\/itc\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/blog.rwth-aachen.de\/itc\/en\/category\/themen\/fun-facts\/#listItem","position":3,"name":"Fun &amp; Facts","item":"https:\/\/blog.rwth-aachen.de\/itc\/en\/category\/themen\/fun-facts\/","nextItem":{"@type":"ListItem","@id":"https:\/\/blog.rwth-aachen.de\/itc\/en\/2019\/04\/26\/78-000\/#listItem","name":"78.000"},"previousItem":{"@type":"ListItem","@id":"https:\/\/blog.rwth-aachen.de\/itc\/en\/category\/themen\/#listItem","name":"Topic"}},{"@type":"ListItem","@id":"https:\/\/blog.rwth-aachen.de\/itc\/en\/2019\/04\/26\/78-000\/#listItem","position":4,"name":"78.000","previousItem":{"@type":"ListItem","@id":"https:\/\/blog.rwth-aachen.de\/itc\/en\/category\/themen\/fun-facts\/#listItem","name":"Fun &amp; Facts"}}]},{"@type":"Organization","@id":"https:\/\/blog.rwth-aachen.de\/itc\/en\/#organization","name":"IT Center RWTH Aachen University","url":"https:\/\/blog.rwth-aachen.de\/itc\/en\/","logo":{"@type":"ImageObject","url":"https:\/\/blog.rwth-aachen.de\/itc\/files\/2018\/09\/IT-Center-Logo.png","@id":"https:\/\/blog.rwth-aachen.de\/itc\/en\/2019\/04\/26\/78-000\/#organizationLogo","width":1312,"height":378,"caption":"IT Center Logo"},"image":{"@id":"https:\/\/blog.rwth-aachen.de\/itc\/en\/2019\/04\/26\/78-000\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/itcenterrwth","https:\/\/twitter.com\/ITCenterRWTH","https:\/\/www.youtube.com\/c\/itcenterrwthaachen","https:\/\/www.linkedin.com\/company\/itcenterrwth"]},{"@type":"Person","@id":"https:\/\/blog.rwth-aachen.de\/itc\/en\/author\/1328\/#author","url":"https:\/\/blog.rwth-aachen.de\/itc\/en\/author\/1328\/","name":"Sara Kaya"},{"@type":"WebPage","@id":"https:\/\/blog.rwth-aachen.de\/itc\/en\/2019\/04\/26\/78-000\/#webpage","url":"https:\/\/blog.rwth-aachen.de\/itc\/en\/2019\/04\/26\/78-000\/","name":"78.000 \u2022 IT Center Blog","description":"Das Backup-Portal bietet eine sichere und verl\u00e4ssliche M\u00f6glichkeit Server in den Instituten auf den Backup-Servern im IT Center versioniert zu sichern und bei Bedarf wiederherzustellen. Es stellt dabei sicher, dass es zu keinem Verlust wissenschaftlicher Daten kommt aufgrund von Defekten an Rechnern und f\u00fcr eine schnelle und sichere Wiederherstellung der Daten gesorgt ist. Allein im Januar 2019 konnte f\u00fcr alle","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/blog.rwth-aachen.de\/itc\/en\/#website"},"breadcrumb":{"@id":"https:\/\/blog.rwth-aachen.de\/itc\/en\/2019\/04\/26\/78-000\/#breadcrumblist"},"author":{"@id":"https:\/\/blog.rwth-aachen.de\/itc\/en\/author\/1328\/#author"},"creator":{"@id":"https:\/\/blog.rwth-aachen.de\/itc\/en\/author\/1328\/#author"},"datePublished":"2019-04-26T13:00:29+02:00","dateModified":"2025-02-24T11:24:42+01:00"},{"@type":"WebSite","@id":"https:\/\/blog.rwth-aachen.de\/itc\/en\/#website","url":"https:\/\/blog.rwth-aachen.de\/itc\/en\/","name":"IT Center Blog","inLanguage":"en-US","publisher":{"@id":"https:\/\/blog.rwth-aachen.de\/itc\/en\/#organization"}}]},"og:locale":"en_US","og:site_name":"IT Center Blog \u2022","og:type":"article","og:title":"78.000 \u2022 IT Center Blog","og:description":"Das Backup-Portal bietet eine sichere und verl\u00e4ssliche M\u00f6glichkeit Server in den Instituten auf den Backup-Servern im IT Center versioniert zu sichern und bei Bedarf wiederherzustellen. Es stellt dabei sicher, dass es zu keinem Verlust wissenschaftlicher Daten kommt aufgrund von Defekten an Rechnern und f\u00fcr eine schnelle und sichere Wiederherstellung der Daten gesorgt ist. Allein im Januar 2019 konnte f\u00fcr alle","og:url":"https:\/\/blog.rwth-aachen.de\/itc\/en\/2019\/04\/26\/78-000\/","article:published_time":"2019-04-26T11:00:29+00:00","article:modified_time":"2025-02-24T10:24:42+00:00","article:publisher":"https:\/\/www.facebook.com\/itcenterrwth","twitter:card":"summary","twitter:site":"@ITCenterRWTH","twitter:title":"78.000 \u2022 IT Center Blog","twitter:description":"Das Backup-Portal bietet eine sichere und verl\u00e4ssliche M\u00f6glichkeit Server in den Instituten auf den Backup-Servern im IT Center versioniert zu sichern und bei Bedarf wiederherzustellen. Es stellt dabei sicher, dass es zu keinem Verlust wissenschaftlicher Daten kommt aufgrund von Defekten an Rechnern und f\u00fcr eine schnelle und sichere Wiederherstellung der Daten gesorgt ist. Allein im Januar 2019 konnte f\u00fcr alle","twitter:creator":"@ITCenterRWTH"},"aioseo_meta_data":{"post_id":"5568","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":{"id":"aioseo-article-63516d0bd87e0","slug":"article","graphName":"Article","label":"Artikel","properties":{"type":"BlogPosting","name":"#post_title","headline":"#post_title","description":"#post_excerpt","image":"","keywords":"","author":{"name":"#author_name","url":"#author_url"},"dates":{"include":true,"datePublished":"","dateModified":""}}},"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2022-01-24 14:29:05","updated":"2025-07-08 13:19:36","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/blog.rwth-aachen.de\/itc\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/blog.rwth-aachen.de\/itc\/en\/category\/themen\/\" title=\"Topic\">Topic<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/blog.rwth-aachen.de\/itc\/en\/category\/themen\/fun-facts\/\" title=\"Fun &amp; Facts\">Fun &amp; Facts<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t78.000\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/blog.rwth-aachen.de\/itc\/en"},{"label":"Topic","link":"https:\/\/blog.rwth-aachen.de\/itc\/en\/category\/themen\/"},{"label":"Fun &amp; Facts","link":"https:\/\/blog.rwth-aachen.de\/itc\/en\/category\/themen\/fun-facts\/"},{"label":"78.000","link":"https:\/\/blog.rwth-aachen.de\/itc\/en\/2019\/04\/26\/78-000\/"}],"_links":{"self":[{"href":"https:\/\/blog.rwth-aachen.de\/itc\/en\/wp-json\/wp\/v2\/posts\/5568","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.rwth-aachen.de\/itc\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.rwth-aachen.de\/itc\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.rwth-aachen.de\/itc\/en\/wp-json\/wp\/v2\/users\/1328"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.rwth-aachen.de\/itc\/en\/wp-json\/wp\/v2\/comments?post=5568"}],"version-history":[{"count":12,"href":"https:\/\/blog.rwth-aachen.de\/itc\/en\/wp-json\/wp\/v2\/posts\/5568\/revisions"}],"predecessor-version":[{"id":21543,"href":"https:\/\/blog.rwth-aachen.de\/itc\/en\/wp-json\/wp\/v2\/posts\/5568\/revisions\/21543"}],"wp:attachment":[{"href":"https:\/\/blog.rwth-aachen.de\/itc\/en\/wp-json\/wp\/v2\/media?parent=5568"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.rwth-aachen.de\/itc\/en\/wp-json\/wp\/v2\/categories?post=5568"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.rwth-aachen.de\/itc\/en\/wp-json\/wp\/v2\/tags?post=5568"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}