{"id":13487,"date":"2022-12-28T13:00:53","date_gmt":"2022-12-28T12:00:53","guid":{"rendered":"https:\/\/blog.rwth-aachen.de\/itc\/?p=13487"},"modified":"2025-02-24T11:18:04","modified_gmt":"2025-02-24T10:18:04","slug":"ssl-zertifikate","status":"publish","type":"post","link":"https:\/\/blog.rwth-aachen.de\/itc\/2022\/12\/28\/ssl-zertifikate\/","title":{"rendered":"Automatisierte SSL-Zertifikate bei gehosteten Webseiten"},"content":{"rendered":"<div class=\"twoclick_social_bookmarks_post_13487 social_share_privacy clearfix 1.6.4 locale-de_DE sprite-de_DE\"><\/div><div class=\"twoclick-js\"><script type=\"text\/javascript\">\/* <![CDATA[ *\/\njQuery(document).ready(function($){if($('.twoclick_social_bookmarks_post_13487')){$('.twoclick_social_bookmarks_post_13487').socialSharePrivacy({\"txt_help\":\"Wenn Sie diese Felder durch einen Klick aktivieren, werden Informationen an Facebook, Twitter, Flattr, Xing, t3n, LinkedIn, Pinterest oder Google eventuell ins Ausland \\u00fcbertragen und unter Umst\\u00e4nden auch dort gespeichert. N\\u00e4heres erfahren Sie durch einen Klick auf das <em>i<\\\/em>.\",\"settings_perma\":\"Dauerhaft aktivieren und Daten\\u00fcber-tragung zustimmen:\",\"info_link\":\"http:\\\/\\\/www.heise.de\\\/ct\\\/artikel\\\/2-Klicks-fuer-mehr-Datenschutz-1333879.html\",\"uri\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/2022\\\/12\\\/28\\\/ssl-zertifikate\\\/\",\"post_id\":13487,\"post_title_referrer_track\":\"Automatisierte+SSL-Zertifikate+bei+gehosteten+Webseiten\",\"display_infobox\":\"on\"});}});\n\/* ]]> *\/<\/script><\/div><p><div id=\"attachment_13488\" style=\"width: 310px\" class=\"wp-caption alignright\"><a href=\"https:\/\/blog.rwth-aachen.de\/itc\/files\/2022\/12\/21902028_6500504-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-13488\" class=\"size-medium wp-image-13488\" src=\"https:\/\/blog.rwth-aachen.de\/itc\/files\/2022\/12\/21902028_6500504-300x231.jpg\" alt=\"Grafische Darstellung einer Webseite\" width=\"300\" height=\"231\" srcset=\"https:\/\/blog.rwth-aachen.de\/itc\/files\/2022\/12\/21902028_6500504-300x231.jpg 300w, https:\/\/blog.rwth-aachen.de\/itc\/files\/2022\/12\/21902028_6500504-1024x788.jpg 1024w, https:\/\/blog.rwth-aachen.de\/itc\/files\/2022\/12\/21902028_6500504-768x591.jpg 768w, https:\/\/blog.rwth-aachen.de\/itc\/files\/2022\/12\/21902028_6500504-1536x1182.jpg 1536w, https:\/\/blog.rwth-aachen.de\/itc\/files\/2022\/12\/21902028_6500504-2048x1575.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-13488\" class=\"wp-caption-text\">Quelle: <a href=\"https:\/\/de.freepik.com\/vektoren-kostenlos\/hand-gezeichnete-flache-design-ssl-illustration_21902028.htm\">Freepik<\/a><\/p><\/div><\/p>\n<p>Endlich ist es so weit. Seit dem 06. Dezember 2022 werden die bei uns gehosteten Webseiten automatisch auf \u201ehttps\u201c umgestellt und mit entsprechenden SSL-Zertifikaten ausgestattet. Das Beste daran? Ihr m\u00fcsst euch um nichts mehr k\u00fcmmern.<br \/>\n<!--more--><\/p>\n<p>&nbsp;<\/p>\n<h3><span style=\"color: #00549f;\"><strong>Was ist ein SSL-Zertifikat und w<\/strong><\/span><span style=\"color: #00549f;\"><strong>of\u00fcr wird es ben\u00f6tigt?<\/strong><\/span><\/h3>\n<p>Server benutzen zur Verschl\u00fcsselung von Daten digitale Zertifikate. Diese digitalen Zertifikate sind als SSL-Zertifikate bekannt. SSL ist die Abk\u00fcrzung f\u00fcr Secure-Socket-Layer. Sie verschl\u00fcsseln Daten, die zwischen einem Webbrowser (z.B. Google Chrome) und einem Webserver ausgetauscht werden. So werden Kommunikationsdaten vor Manipulation gesch\u00fctzt. Durch ein SSL-Zertifikat wird die Integrit\u00e4t und die Vertraulichkeit der Website \u00fcberpr\u00fcft und verdeutlicht.\u00a0 Das funktioniert so:<\/p>\n<ol>\n<li>Der Webserver sendet eine Kopie seines SSL-Zertifikates an den Webbrowser<\/li>\n<li>Der Webbrowser kontrolliert, ob das Zertifikat vertrauensw\u00fcrdig ist<\/li>\n<li>Wenn ja, sendet er das &#8222;OK&#8220; an den Webserver<\/li>\n<li>Der Webserver sendet eine digital signierte Best\u00e4tigung und leitet eine verschl\u00fcsselte SSL-Sitzung ein<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<h3><span style=\"color: #00549f;\"><strong>Und was ist jetzt neu?<\/strong><\/span><\/h3>\n<p>Die Zertifikate f\u00fcr alle Webseiten werden ab sofort automatisch erstellt und zuk\u00fcnftig auch automatisch erneuert. F\u00fcr die Webseiten Inhaber*innen entf\u00e4llt somit der Aufwand regelm\u00e4\u00dfig ein neues Zertifikat zu erstellen. Und das gilt sowohl f\u00fcr bestehende als auch f\u00fcr zuk\u00fcnftige Webseiten!<\/p>\n<p>&nbsp;<\/p>\n<h3><span style=\"color: #00549f;\"><strong>Was ist, wenn meine Seite bisher noch kein SSL-Zertifikat hatte?<\/strong><\/span><\/h3>\n<p>Die Zertifikate f\u00fcr die Seiten werden automatisch erstellt und zuk\u00fcnftig dann auch erneuert. Damit das Zertifikat aber richtig auf der Seite eingebettet ist, m\u00fcsst ihr pr\u00fcfen, ob \u00c4nderungen in der Konfiguration der Basis-URL notwendig sind. Je nachdem ob und welches Content-Management-System zum Betrieb der Seite verwendet wird, muss die Basis-URL in der Konfiguration auf \u201ehttps\u201c umstellt werden.<\/p>\n<p>Beispielsweise:  anstatt <\/p>\n<p>&nbsp;<\/p>\n<h3><span style=\"color: #00549f;\"><strong>Warum ist eine automatisierte Erstellung von Zertifikaten sinnvoll?<\/strong><\/span><\/h3>\n<p>Die Umstellung bringt einige Vorteile mit sich. In Zukunft werden die Webseiten bereits direkt im Rahmen der Bestellung mit einem SSL-Zertifikat ausgestattet. \u00a0Au\u00dferdem erhalten die Nutzenden der Webseiten zuk\u00fcnftig keine Sicherheitswarnungen mehr, wenn sie die Webseite aufrufen und das Zertifikat fehlt oder abgelaufen ist. Dar\u00fcber hinaus ist der grunds\u00e4tzliche Vorteil, wie oben bereits beschrieben, der verschl\u00fcsselte Datenverkehr, welcher zu einer erh\u00f6hten Sicherheit der Seite f\u00fchrt.<\/p>\n<p>Das Beste ist jedoch, dass ihr euch in Zukunft keine Gedanken mehr \u00fcber die Laufzeit eurer Zertifikate machen m\u00fcsst. Diese werden einfach automatisch verl\u00e4ngert.<\/p>\n<p>Verantwortlich f\u00fcr die Inhalte dieses Beitrags sind <a href=\"https:\/\/www.itc.rwth-aachen.de\/cms\/IT-Center\/IT-Center\/Team\/~epvp\/Mitarbeiter-CAMPUS-\/?gguid=0x4CB2701C1FEE5447B1BB5BF4FC8E5641&amp;allou=1\">Katharina R\u00f6hrig<\/a> und <a href=\"https:\/\/www.itc.rwth-aachen.de\/cms\/it-center\/IT-Center\/Profil\/Team\/~epvp\/Mitarbeiter-CAMPUS-\/?gguid=0x592B0D17C73A1249AC2C233FADF6EE96&amp;allou=1\">Janin Vreydal<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Endlich ist es so weit. Seit dem 06. Dezember 2022 werden die bei uns gehosteten Webseiten automatisch auf \u201ehttps\u201c umgestellt und mit entsprechenden SSL-Zertifikaten ausgestattet. Das Beste daran? Ihr m\u00fcsst [&hellip;]<\/p>\n","protected":false},"author":3351,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"c2c_always_allow_admin_comments":false,"footnotes":""},"categories":[306,314,315],"tags":[742,740,741],"class_list":["post-13487","post","type-post","status-publish","format-standard","hentry","category-ankuendigungen","category-it-sicherheit","category-services-support","tag-hosting","tag-ssl","tag-webseiten"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.8 - aioseo.com -->\n\t<meta name=\"description\" content=\"Quelle: Freepik Endlich ist es so weit. Seit dem 06. Dezember 2022 werden die bei uns gehosteten Webseiten automatisch auf \u201ehttps\u201c umgestellt und mit entsprechenden SSL-Zertifikaten ausgestattet. Das Beste daran? Ihr m\u00fcsst euch um nichts mehr k\u00fcmmern. Was ist ein SSL-Zertifikat und wof\u00fcr wird es ben\u00f6tigt? Server benutzen zur Verschl\u00fcsselung von Daten digitale Zertifikate.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Iglauer Janin\"\/>\n\t<meta name=\"keywords\" content=\"hosting,ssl,webseiten,ank\u00fcndigungen,it-sicherheit,services &amp; support\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/blog.rwth-aachen.de\/itc\/2022\/12\/28\/ssl-zertifikate\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.8\" \/>\n\t\t<meta property=\"og:locale\" content=\"de_DE\" \/>\n\t\t<meta property=\"og:site_name\" content=\"IT Center Blog \u2022\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Automatisierte SSL-Zertifikate bei gehosteten Webseiten \u2022 IT Center Blog\" \/>\n\t\t<meta property=\"og:description\" content=\"Quelle: Freepik Endlich ist es so weit. Seit dem 06. Dezember 2022 werden die bei uns gehosteten Webseiten automatisch auf \u201ehttps\u201c umgestellt und mit entsprechenden SSL-Zertifikaten ausgestattet. Das Beste daran? Ihr m\u00fcsst euch um nichts mehr k\u00fcmmern. Was ist ein SSL-Zertifikat und wof\u00fcr wird es ben\u00f6tigt? Server benutzen zur Verschl\u00fcsselung von Daten digitale Zertifikate.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/blog.rwth-aachen.de\/itc\/2022\/12\/28\/ssl-zertifikate\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2022-12-28T12:00:53+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-02-24T10:18:04+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/itcenterrwth\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@ITCenterRWTH\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Automatisierte SSL-Zertifikate bei gehosteten Webseiten \u2022 IT Center Blog\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Quelle: Freepik Endlich ist es so weit. Seit dem 06. Dezember 2022 werden die bei uns gehosteten Webseiten automatisch auf \u201ehttps\u201c umgestellt und mit entsprechenden SSL-Zertifikaten ausgestattet. Das Beste daran? Ihr m\u00fcsst euch um nichts mehr k\u00fcmmern. Was ist ein SSL-Zertifikat und wof\u00fcr wird es ben\u00f6tigt? Server benutzen zur Verschl\u00fcsselung von Daten digitale Zertifikate.\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@ITCenterRWTH\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/2022\\\/12\\\/28\\\/ssl-zertifikate\\\/#blogposting\",\"name\":\"Automatisierte SSL-Zertifikate bei gehosteten Webseiten \\u2022 IT Center Blog\",\"headline\":\"Automatisierte SSL-Zertifikate bei gehosteten Webseiten\",\"author\":{\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/author\\\/3351\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/files\\\/2022\\\/12\\\/21902028_6500504.jpg\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/2022\\\/12\\\/28\\\/ssl-zertifikate\\\/#articleImage\"},\"datePublished\":\"2022-12-28T13:00:53+01:00\",\"dateModified\":\"2025-02-24T11:18:04+01:00\",\"inLanguage\":\"de-DE\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/2022\\\/12\\\/28\\\/ssl-zertifikate\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/2022\\\/12\\\/28\\\/ssl-zertifikate\\\/#webpage\"},\"articleSection\":\"Ank\\u00fcndigungen, IT-Sicherheit, Services &amp; Support, Hosting, SSL, Webseiten\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/2022\\\/12\\\/28\\\/ssl-zertifikate\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/category\\\/themen\\\/#listItem\",\"name\":\"Themen\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/category\\\/themen\\\/#listItem\",\"position\":2,\"name\":\"Themen\",\"item\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/category\\\/themen\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/category\\\/themen\\\/ankuendigungen\\\/#listItem\",\"name\":\"Ank\\u00fcndigungen\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/category\\\/themen\\\/ankuendigungen\\\/#listItem\",\"position\":3,\"name\":\"Ank\\u00fcndigungen\",\"item\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/category\\\/themen\\\/ankuendigungen\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/2022\\\/12\\\/28\\\/ssl-zertifikate\\\/#listItem\",\"name\":\"Automatisierte SSL-Zertifikate bei gehosteten Webseiten\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/category\\\/themen\\\/#listItem\",\"name\":\"Themen\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/2022\\\/12\\\/28\\\/ssl-zertifikate\\\/#listItem\",\"position\":4,\"name\":\"Automatisierte SSL-Zertifikate bei gehosteten Webseiten\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/category\\\/themen\\\/ankuendigungen\\\/#listItem\",\"name\":\"Ank\\u00fcndigungen\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/#organization\",\"name\":\"IT Center RWTH Aachen University\",\"url\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/files\\\/2018\\\/09\\\/IT-Center-Logo.png\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/2022\\\/12\\\/28\\\/ssl-zertifikate\\\/#organizationLogo\",\"width\":1312,\"height\":378,\"caption\":\"IT Center Logo\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/2022\\\/12\\\/28\\\/ssl-zertifikate\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/itcenterrwth\",\"https:\\\/\\\/twitter.com\\\/ITCenterRWTH\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/itcenterrwthaachen\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/itcenterrwth\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/author\\\/3351\\\/#author\",\"url\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/author\\\/3351\\\/\",\"name\":\"Iglauer Janin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/2022\\\/12\\\/28\\\/ssl-zertifikate\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ae369f866db7f1929e2bb64d8f27ac1a2cf89e7b423120d736b16c1aa0ee4880?s=96&d=blank&r=g\",\"width\":96,\"height\":96,\"caption\":\"Iglauer Janin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/2022\\\/12\\\/28\\\/ssl-zertifikate\\\/#webpage\",\"url\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/2022\\\/12\\\/28\\\/ssl-zertifikate\\\/\",\"name\":\"Automatisierte SSL-Zertifikate bei gehosteten Webseiten \\u2022 IT Center Blog\",\"description\":\"Quelle: Freepik Endlich ist es so weit. Seit dem 06. Dezember 2022 werden die bei uns gehosteten Webseiten automatisch auf \\u201ehttps\\u201c umgestellt und mit entsprechenden SSL-Zertifikaten ausgestattet. Das Beste daran? Ihr m\\u00fcsst euch um nichts mehr k\\u00fcmmern. Was ist ein SSL-Zertifikat und wof\\u00fcr wird es ben\\u00f6tigt? Server benutzen zur Verschl\\u00fcsselung von Daten digitale Zertifikate.\",\"inLanguage\":\"de-DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/2022\\\/12\\\/28\\\/ssl-zertifikate\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/author\\\/3351\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/author\\\/3351\\\/#author\"},\"datePublished\":\"2022-12-28T13:00:53+01:00\",\"dateModified\":\"2025-02-24T11:18:04+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/#website\",\"url\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/\",\"name\":\"IT Center Blog\",\"inLanguage\":\"de-DE\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Automatisierte SSL-Zertifikate bei gehosteten Webseiten \u2022 IT Center Blog","description":"Quelle: Freepik Endlich ist es so weit. Seit dem 06. Dezember 2022 werden die bei uns gehosteten Webseiten automatisch auf \u201ehttps\u201c umgestellt und mit entsprechenden SSL-Zertifikaten ausgestattet. Das Beste daran? Ihr m\u00fcsst euch um nichts mehr k\u00fcmmern. Was ist ein SSL-Zertifikat und wof\u00fcr wird es ben\u00f6tigt? Server benutzen zur Verschl\u00fcsselung von Daten digitale Zertifikate.","canonical_url":"https:\/\/blog.rwth-aachen.de\/itc\/2022\/12\/28\/ssl-zertifikate\/","robots":"max-image-preview:large","keywords":"hosting,ssl,webseiten,ank\u00fcndigungen,it-sicherheit,services &amp; support","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/blog.rwth-aachen.de\/itc\/2022\/12\/28\/ssl-zertifikate\/#blogposting","name":"Automatisierte SSL-Zertifikate bei gehosteten Webseiten \u2022 IT Center Blog","headline":"Automatisierte SSL-Zertifikate bei gehosteten Webseiten","author":{"@id":"https:\/\/blog.rwth-aachen.de\/itc\/author\/3351\/#author"},"publisher":{"@id":"https:\/\/blog.rwth-aachen.de\/itc\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/blog.rwth-aachen.de\/itc\/files\/2022\/12\/21902028_6500504.jpg","@id":"https:\/\/blog.rwth-aachen.de\/itc\/2022\/12\/28\/ssl-zertifikate\/#articleImage"},"datePublished":"2022-12-28T13:00:53+01:00","dateModified":"2025-02-24T11:18:04+01:00","inLanguage":"de-DE","mainEntityOfPage":{"@id":"https:\/\/blog.rwth-aachen.de\/itc\/2022\/12\/28\/ssl-zertifikate\/#webpage"},"isPartOf":{"@id":"https:\/\/blog.rwth-aachen.de\/itc\/2022\/12\/28\/ssl-zertifikate\/#webpage"},"articleSection":"Ank\u00fcndigungen, IT-Sicherheit, Services &amp; Support, Hosting, SSL, Webseiten"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.rwth-aachen.de\/itc\/2022\/12\/28\/ssl-zertifikate\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/blog.rwth-aachen.de\/itc#listItem","position":1,"name":"Home","item":"https:\/\/blog.rwth-aachen.de\/itc","nextItem":{"@type":"ListItem","@id":"https:\/\/blog.rwth-aachen.de\/itc\/category\/themen\/#listItem","name":"Themen"}},{"@type":"ListItem","@id":"https:\/\/blog.rwth-aachen.de\/itc\/category\/themen\/#listItem","position":2,"name":"Themen","item":"https:\/\/blog.rwth-aachen.de\/itc\/category\/themen\/","nextItem":{"@type":"ListItem","@id":"https:\/\/blog.rwth-aachen.de\/itc\/category\/themen\/ankuendigungen\/#listItem","name":"Ank\u00fcndigungen"},"previousItem":{"@type":"ListItem","@id":"https:\/\/blog.rwth-aachen.de\/itc#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/blog.rwth-aachen.de\/itc\/category\/themen\/ankuendigungen\/#listItem","position":3,"name":"Ank\u00fcndigungen","item":"https:\/\/blog.rwth-aachen.de\/itc\/category\/themen\/ankuendigungen\/","nextItem":{"@type":"ListItem","@id":"https:\/\/blog.rwth-aachen.de\/itc\/2022\/12\/28\/ssl-zertifikate\/#listItem","name":"Automatisierte SSL-Zertifikate bei gehosteten Webseiten"},"previousItem":{"@type":"ListItem","@id":"https:\/\/blog.rwth-aachen.de\/itc\/category\/themen\/#listItem","name":"Themen"}},{"@type":"ListItem","@id":"https:\/\/blog.rwth-aachen.de\/itc\/2022\/12\/28\/ssl-zertifikate\/#listItem","position":4,"name":"Automatisierte SSL-Zertifikate bei gehosteten Webseiten","previousItem":{"@type":"ListItem","@id":"https:\/\/blog.rwth-aachen.de\/itc\/category\/themen\/ankuendigungen\/#listItem","name":"Ank\u00fcndigungen"}}]},{"@type":"Organization","@id":"https:\/\/blog.rwth-aachen.de\/itc\/#organization","name":"IT Center RWTH Aachen University","url":"https:\/\/blog.rwth-aachen.de\/itc\/","logo":{"@type":"ImageObject","url":"https:\/\/blog.rwth-aachen.de\/itc\/files\/2018\/09\/IT-Center-Logo.png","@id":"https:\/\/blog.rwth-aachen.de\/itc\/2022\/12\/28\/ssl-zertifikate\/#organizationLogo","width":1312,"height":378,"caption":"IT Center Logo"},"image":{"@id":"https:\/\/blog.rwth-aachen.de\/itc\/2022\/12\/28\/ssl-zertifikate\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/itcenterrwth","https:\/\/twitter.com\/ITCenterRWTH","https:\/\/www.youtube.com\/c\/itcenterrwthaachen","https:\/\/www.linkedin.com\/company\/itcenterrwth"]},{"@type":"Person","@id":"https:\/\/blog.rwth-aachen.de\/itc\/author\/3351\/#author","url":"https:\/\/blog.rwth-aachen.de\/itc\/author\/3351\/","name":"Iglauer Janin","image":{"@type":"ImageObject","@id":"https:\/\/blog.rwth-aachen.de\/itc\/2022\/12\/28\/ssl-zertifikate\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/ae369f866db7f1929e2bb64d8f27ac1a2cf89e7b423120d736b16c1aa0ee4880?s=96&d=blank&r=g","width":96,"height":96,"caption":"Iglauer Janin"}},{"@type":"WebPage","@id":"https:\/\/blog.rwth-aachen.de\/itc\/2022\/12\/28\/ssl-zertifikate\/#webpage","url":"https:\/\/blog.rwth-aachen.de\/itc\/2022\/12\/28\/ssl-zertifikate\/","name":"Automatisierte SSL-Zertifikate bei gehosteten Webseiten \u2022 IT Center Blog","description":"Quelle: Freepik Endlich ist es so weit. Seit dem 06. Dezember 2022 werden die bei uns gehosteten Webseiten automatisch auf \u201ehttps\u201c umgestellt und mit entsprechenden SSL-Zertifikaten ausgestattet. Das Beste daran? Ihr m\u00fcsst euch um nichts mehr k\u00fcmmern. Was ist ein SSL-Zertifikat und wof\u00fcr wird es ben\u00f6tigt? Server benutzen zur Verschl\u00fcsselung von Daten digitale Zertifikate.","inLanguage":"de-DE","isPartOf":{"@id":"https:\/\/blog.rwth-aachen.de\/itc\/#website"},"breadcrumb":{"@id":"https:\/\/blog.rwth-aachen.de\/itc\/2022\/12\/28\/ssl-zertifikate\/#breadcrumblist"},"author":{"@id":"https:\/\/blog.rwth-aachen.de\/itc\/author\/3351\/#author"},"creator":{"@id":"https:\/\/blog.rwth-aachen.de\/itc\/author\/3351\/#author"},"datePublished":"2022-12-28T13:00:53+01:00","dateModified":"2025-02-24T11:18:04+01:00"},{"@type":"WebSite","@id":"https:\/\/blog.rwth-aachen.de\/itc\/#website","url":"https:\/\/blog.rwth-aachen.de\/itc\/","name":"IT Center Blog","inLanguage":"de-DE","publisher":{"@id":"https:\/\/blog.rwth-aachen.de\/itc\/#organization"}}]},"og:locale":"de_DE","og:site_name":"IT Center Blog \u2022","og:type":"article","og:title":"Automatisierte SSL-Zertifikate bei gehosteten Webseiten \u2022 IT Center Blog","og:description":"Quelle: Freepik Endlich ist es so weit. Seit dem 06. Dezember 2022 werden die bei uns gehosteten Webseiten automatisch auf \u201ehttps\u201c umgestellt und mit entsprechenden SSL-Zertifikaten ausgestattet. Das Beste daran? Ihr m\u00fcsst euch um nichts mehr k\u00fcmmern. Was ist ein SSL-Zertifikat und wof\u00fcr wird es ben\u00f6tigt? Server benutzen zur Verschl\u00fcsselung von Daten digitale Zertifikate.","og:url":"https:\/\/blog.rwth-aachen.de\/itc\/2022\/12\/28\/ssl-zertifikate\/","article:published_time":"2022-12-28T12:00:53+00:00","article:modified_time":"2025-02-24T10:18:04+00:00","article:publisher":"https:\/\/www.facebook.com\/itcenterrwth","twitter:card":"summary","twitter:site":"@ITCenterRWTH","twitter:title":"Automatisierte SSL-Zertifikate bei gehosteten Webseiten \u2022 IT Center Blog","twitter:description":"Quelle: Freepik Endlich ist es so weit. Seit dem 06. Dezember 2022 werden die bei uns gehosteten Webseiten automatisch auf \u201ehttps\u201c umgestellt und mit entsprechenden SSL-Zertifikaten ausgestattet. Das Beste daran? Ihr m\u00fcsst euch um nichts mehr k\u00fcmmern. Was ist ein SSL-Zertifikat und wof\u00fcr wird es ben\u00f6tigt? Server benutzen zur Verschl\u00fcsselung von Daten digitale Zertifikate.","twitter:creator":"@ITCenterRWTH"},"aioseo_meta_data":{"post_id":"13487","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"SSL","score":88,"analysis":{"keyphraseInTitle":{"title":"Focus keyphrase in SEO title","description":"Focus keyphrase found in SEO title.","score":9,"maxScore":9,"error":0},"keyphraseInDescription":[],"keyphraseLength":{"title":"Focus keyphrase length","description":"Good job!","score":9,"maxScore":9,"error":0,"length":1},"keyphraseInURL":{"title":"Focus keyphrase in URL","description":"Focus keyphrase used in the URL.","score":5,"maxScore":5,"error":0},"keyphraseInIntroduction":{"title":"Focus keyphrase in introduction","description":"Your Focus keyphrase appears in the first paragraph. Well done!","score":9,"maxScore":9,"error":0},"keyphraseInSubHeadings":{"title":"Focus keyphrase in Subheadings","description":"Your H2 and H3 subheadings reflects the topic of your copy. Good job!","score":9,"maxScore":9,"error":0},"keyphraseInImageAlt":{"title":"Focus keyphrase in image alt attributes","description":"Focus keyphrase not found in image alt attribute(s). Add an image with your Focus keyphrase as alt text.","score":3,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2022-12-21 16:13:44","updated":"2025-07-08 14:16:31","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/blog.rwth-aachen.de\/itc\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/blog.rwth-aachen.de\/itc\/category\/themen\/\" title=\"Themen\">Themen<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/blog.rwth-aachen.de\/itc\/category\/themen\/ankuendigungen\/\" title=\"Ank\u00fcndigungen\">Ank\u00fcndigungen<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tAutomatisierte SSL-Zertifikate bei gehosteten Webseiten\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/blog.rwth-aachen.de\/itc"},{"label":"Themen","link":"https:\/\/blog.rwth-aachen.de\/itc\/category\/themen\/"},{"label":"Ank\u00fcndigungen","link":"https:\/\/blog.rwth-aachen.de\/itc\/category\/themen\/ankuendigungen\/"},{"label":"Automatisierte SSL-Zertifikate bei gehosteten Webseiten","link":"https:\/\/blog.rwth-aachen.de\/itc\/2022\/12\/28\/ssl-zertifikate\/"}],"_links":{"self":[{"href":"https:\/\/blog.rwth-aachen.de\/itc\/wp-json\/wp\/v2\/posts\/13487","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.rwth-aachen.de\/itc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.rwth-aachen.de\/itc\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.rwth-aachen.de\/itc\/wp-json\/wp\/v2\/users\/3351"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.rwth-aachen.de\/itc\/wp-json\/wp\/v2\/comments?post=13487"}],"version-history":[{"count":23,"href":"https:\/\/blog.rwth-aachen.de\/itc\/wp-json\/wp\/v2\/posts\/13487\/revisions"}],"predecessor-version":[{"id":21514,"href":"https:\/\/blog.rwth-aachen.de\/itc\/wp-json\/wp\/v2\/posts\/13487\/revisions\/21514"}],"wp:attachment":[{"href":"https:\/\/blog.rwth-aachen.de\/itc\/wp-json\/wp\/v2\/media?parent=13487"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.rwth-aachen.de\/itc\/wp-json\/wp\/v2\/categories?post=13487"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.rwth-aachen.de\/itc\/wp-json\/wp\/v2\/tags?post=13487"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}