{"id":19328,"date":"2024-05-15T11:30:20","date_gmt":"2024-05-15T09:30:20","guid":{"rendered":"https:\/\/blog.rwth-aachen.de\/itc\/?p=19328"},"modified":"2024-05-15T16:04:34","modified_gmt":"2024-05-15T14:04:34","slug":"hpc-landingpage","status":"publish","type":"post","link":"https:\/\/blog.rwth-aachen.de\/itc\/2024\/05\/15\/hpc-landingpage\/","title":{"rendered":"HPC-Landingpage: Hochleistungsrechnen"},"content":{"rendered":"<div class=\"twoclick_social_bookmarks_post_19328 social_share_privacy clearfix 1.6.4 locale-de_DE sprite-de_DE\"><\/div><div class=\"twoclick-js\"><script type=\"text\/javascript\">\/* <![CDATA[ *\/\njQuery(document).ready(function($){if($('.twoclick_social_bookmarks_post_19328')){$('.twoclick_social_bookmarks_post_19328').socialSharePrivacy({\"txt_help\":\"Wenn Sie diese Felder durch einen Klick aktivieren, werden Informationen an Facebook, Twitter, Flattr, Xing, t3n, LinkedIn, Pinterest oder Google eventuell ins Ausland \\u00fcbertragen und unter Umst\\u00e4nden auch dort gespeichert. N\\u00e4heres erfahren Sie durch einen Klick auf das <em>i<\\\/em>.\",\"settings_perma\":\"Dauerhaft aktivieren und Daten\\u00fcber-tragung zustimmen:\",\"info_link\":\"http:\\\/\\\/www.heise.de\\\/ct\\\/artikel\\\/2-Klicks-fuer-mehr-Datenschutz-1333879.html\",\"uri\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/2024\\\/05\\\/15\\\/hpc-landingpage\\\/\",\"post_id\":19328,\"post_title_referrer_track\":\"HPC-Landingpage%3A+Hochleistungsrechnen\",\"display_infobox\":\"on\"});}});\n\/* ]]> *\/<\/script><\/div><p><div id=\"attachment_19363\" style=\"width: 310px\" class=\"wp-caption alignright\"><a href=\"https:\/\/blog.rwth-aachen.de\/itc\/files\/2024\/05\/RWTH-HPC-News-2_3.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-19363\" class=\"wp-image-19363 size-medium\" src=\"https:\/\/blog.rwth-aachen.de\/itc\/files\/2024\/05\/RWTH-HPC-News-2_3-300x201.jpg\" alt=\"\" width=\"300\" height=\"201\" srcset=\"https:\/\/blog.rwth-aachen.de\/itc\/files\/2024\/05\/RWTH-HPC-News-2_3-300x201.jpg 300w, https:\/\/blog.rwth-aachen.de\/itc\/files\/2024\/05\/RWTH-HPC-News-2_3-1024x685.jpg 1024w, https:\/\/blog.rwth-aachen.de\/itc\/files\/2024\/05\/RWTH-HPC-News-2_3-768x514.jpg 768w, https:\/\/blog.rwth-aachen.de\/itc\/files\/2024\/05\/RWTH-HPC-News-2_3.jpg 1480w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-19363\" class=\"wp-caption-text\">Quelle: Eigene Darstellung<\/p><\/div><\/p>\n<p>Das Hochleistungsrechnen (HPC) an der RWTH Aachen fungiert als zentraler Baustein zur Unterst\u00fctzung der Simulationswissenschaften, indem es die Entwicklung skalierbarer Algorithmen und Software erm\u00f6glicht. Von zentraler Bedeutung f\u00fcr Innovationen in Wirtschaft und Gesellschaft bietet das RWTH Hochleistungsrechnen diverse Services und Forschungsm\u00f6glichkeiten auf Basis einer erstklassigen Infrastruktur. So k\u00f6nnen HPC-Anwendungen skalierbar und effizient ausgef\u00fchrt und gro\u00dfe Datenmengen sicher und schnell verarbeitet werden.<\/p>\n<p>Die Umsetzung wird durch Projekte wie\u00a0beispielsweise <a href=\"https:\/\/www.jara.org\/de\/\">JARA<\/a>, <a href=\"https:\/\/hpc.dh.nrw\/de\/\">HPC.NRW<\/a> sowie insbesondere durch das nationale\u00a0<a href=\"https:\/\/nhr4ces.de\/\">Hochleistungsrechenzentrum f\u00fcr Computational Engineering Science (NHR4CES)<\/a> unterst\u00fctzt. Mehr dazu k\u00f6nnt ihr unter der <a href=\"https:\/\/blog.rwth-aachen.de\/itc\/category\/themen\/hpcnews\/\">Kategorie HPCnews <\/a>lesen.<\/p>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<h3><span style=\"color: #00549f;\">Cluster Aix-la-Chapelle (CLAIX)<\/span><\/h3>\n<p>Das Herzst\u00fcck des HPC-\u00d6kosystems ist der\u00a0<a href=\"https:\/\/www.itc.rwth-aachen.de\/go\/id\/bcepsh\">Cluster Aix-la-Chapelle (CLAIX)<\/a>\u00a0des IT Centers, der verschiedene Ausbaustufen umfasst. CLAIX-2023 wurde vor Kurzem mit modernster Technologie wie Intel Xeon Sapphire Rapids Prozessoren und NVIDIA H100 Beschleunigern in Betrieb genommen. Dies erm\u00f6glicht die Ausf\u00fchrung einer breiten Palette von Anwendungen, die von den Ingenieurwissenschaften bis hin zur k\u00fcnstlichen Intelligenz und maschinellem Lernen reicht.<\/p>\n<p>CLAIX fasst die verschiedenen Ausbaustufen des Hochleistungsrechners (HPC-System) und der Datenspeicher an der RWTH Aachen zusammen. Das aktuelle System besteht aus den Ausbaustufen CLAIX-2023 und CLAIX-2018 und mehreren Dateisystemen f\u00fcr unterschiedliche <a href=\"https:\/\/www.hpc.itc.rwth-aachen.de\/cms\/hpc\/Systeme-Services\/~bcepsh\/Systeme\/\">Aufgabenbereiche<\/a>.<\/p>\n<p>&nbsp;<\/p>\n<h3><span style=\"color: #00549f;\">Kr\u00e4fte b\u00fcndeln<\/span><\/h3>\n<p>Die Computational Engineering Sciences (CES) der RWTH Aachen bilden einen Schwerpunkt, der sich auf Ingenieurwissenschaften, Materialwissenschaften, Physik, Chemie und Informatik erstreckt.<\/p>\n<p>Die HPC-Infrastruktur und Unterst\u00fctzungsprojekte an der RWTH werden geb\u00fcndelt, um ihre individuellen St\u00e4rken zu kombinieren und ein HPC-\u00d6kosystem zu schaffen, das Best Practices von HPC und\u00a0<a href=\"https:\/\/www.hpc.itc.rwth-aachen.de\/go\/id\/lnaw\">Forschungsdatenmanagement<\/a>\u00a0vereint.<\/p>\n<p>Die HPC-Forschung rund um parallele Programmierung und Leistungswerkzeuge wird am\u00a0<a href=\"https:\/\/www.hpc.itc.rwth-aachen.de\/go\/id\/felz\">Lehrstuhl f\u00fcr Hochleistungsrechnen (Informatik 12<\/a>) im Fachbereich Informatik durchgef\u00fchrt, der eng mit dem IT Center verbunden ist. Das 2021 gegr\u00fcndete Hochleistungsrechenzentrum <a href=\"https:\/\/nhr4ces.de\/\">NHR4CES<\/a> spielt als Teil des\u00a0<a href=\"https:\/\/www.nhr-verein.de\/\">Vereins f\u00fcr Nationales H\u00f6chstleistungsrechnen<\/a>\u00a0in Deutschland (NHR) eine entscheidende Rolle bei der Bereitstellung von Rechenkapazit\u00e4ten f\u00fcr Forscherinnen und Forscher an deutschen Hochschulen. Der NHR-Verein bietet einen koordinierten Beratungsdienst zur Methodenkompetenz des wissenschaftlichen Hochleistungsrechnens an. Ziel ist es, Wissenschaftlerinnen und Wissenschaftlern an deutschen Hochschulen Hilfe bei der Beantragung von Rechenkapazit\u00e4ten zu geben, um ihre F\u00e4higkeiten zur effizienten Nutzung dieser Ressource zu st\u00e4rken.<\/p>\n<p>Das Nordrhein-Westf\u00e4lische Kompetenznetzwerk f\u00fcr Hochleistungsrechnen (<a href=\"https:\/\/hpc.dh.nrw\/de\/\">HPC.NRW<\/a>) ist eine kompetente und thematisch breit aufgestellte Anlauf- und Beratungsstelle f\u00fcr Nutzende der HPC-Systeme in NRW.<\/p>\n<p>Das KI-Servicezentrum <a href=\"https:\/\/westai.de\/\">WestAI<\/a>\u00a0erm\u00f6glicht Akteuren aus Wirtschaft und Wissenschaft Zugang zu KI-Modellen und leistungsstarken KI-Recheninfrastrukturen. Es unterst\u00fctzt Start-Ups sowie kleine und mittelst\u00e4ndische Unternehmen dabei, hochmoderne KI-Technologien f\u00fcr sich zu nutzen. Die <a href=\"https:\/\/westai.de\/services\/\">Services<\/a> sind angelehnt an die bekannten Angebote im HPC und reichen KI-spezifisch von der ausf\u00fchrlichen Beratung zur jeweils individuellen KI-Herausforderung \u00fcber deren Realisierung bis hin zur M\u00f6glichkeit, eine unserer zahlreichen KI-Schulungen zu besuchen.<\/p>\n<p>&nbsp;<\/p>\n<h3><span style=\"color: #00549f;\">Services des RWTH Hochleistungsrechnens<\/span><\/h3>\n<p>Durch die oben genannten Netzwerke bietet das Hochleistungsrechnen ein vielf\u00e4ltiges <a href=\"https:\/\/www.hpc.itc.rwth-aachen.de\/cms\/hpc\/Systeme-Services\/~bfwamm\/Services-Support\/\">Service- und Supportangebot<\/a> zur erfolgreichen Nutzung unserer Systeme. Dazu geh\u00f6ren Beratung, insbesondere die Leistungsanalyse und -verbesserung von Anwendungen, Schulungen im Bereich des Hochleistungsrechnens und der parallelen Programmierung, sowie umfassende Unterst\u00fctzung bei der Nutzung von CLAIX. Diese Services zielen darauf ab, Forscherinnen und Forschern in ihren wissenschaftlichen Anwendungsgebieten zu unterst\u00fctzen und die effiziente Nutzung des HPC-Systems zu f\u00f6rdern.<\/p>\n<p>&nbsp;<\/p>\n<h3><span style=\"color: #00549f;\">HPC-Landingpage<\/span><\/h3>\n<p>Um f\u00fcr alle aktuellen und potenziellen Nutzenden sowie interessierten Personen einen zentralen Einstiegspunkt f\u00fcr das Thema RWTH Hochleistungsrechnen zu schaffen, b\u00fcndelt die HPC-Landingpage einen \u00dcberblick \u00fcber aktuelle Forschungsprojekte, die angebotenen Services und Veranstaltungen sowie Informationen zur Nutzung der RWTH-Systeme.<\/p>\n<p>Ihr m\u00f6chtet euch intensiver mit dem Thema RWTH Hochleistungsrechnen besch\u00e4ftigen und mehr dar\u00fcber erfahren? Besucht unsere <a href=\"https:\/\/www.hpc.itc.rwth-aachen.de\/cms\/~bcenat\/hpc\/\">Landingpage<\/a> und verschafft euch einen \u00dcberblick.<\/p>\n<p>&nbsp;<\/p>\n<hr \/>\n<p>Verantwortlich f\u00fcr die Inhalte dieses Beitrags ist <a href=\"https:\/\/www.itc.rwth-aachen.de\/cms\/it-center\/it-center\/profil\/team\/~ooap\/dr-rer-nat-christian-terboven\/?allou=1\">Christian Terboven<\/a> und <a href=\"https:\/\/www.itc.rwth-aachen.de\/cms\/it-center\/it-center\/profil\/team\/~epvp\/mitarbeiter-campus-\/?gguid=PER-FV6GWWB&amp;allou=1\">Janin Iglauer<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Das Hochleistungsrechnen (HPC) an der RWTH Aachen fungiert als zentraler Baustein zur Unterst\u00fctzung der Simulationswissenschaften, indem es die Entwicklung skalierbarer Algorithmen und Software erm\u00f6glicht. Von zentraler Bedeutung f\u00fcr Innovationen in [&hellip;]<\/p>\n","protected":false},"author":5003,"featured_media":19329,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"c2c_always_allow_admin_comments":false,"footnotes":""},"categories":[306,311,924,312,316,315],"tags":[151,1084,1085,159,24,23,471,1131,158,167,799],"class_list":["post-19328","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ankuendigungen","category-fun-facts","category-hpcnews","category-insight-it-center","category-projekte-kooperationen","category-services-support","tag-claix","tag-claix-2023","tag-claix-23","tag-hochleistungsrechnen","tag-hochleistungsrechner","tag-hpc","tag-hpc-nrw","tag-informatik","tag-nhr","tag-nhr4ces","tag-rwth-hpc"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.8 - aioseo.com -->\n\t<meta name=\"description\" content=\"Um f\u00fcr alle Nutzenden einen Einstiegspunkt f\u00fcr HPC zu schaffen, b\u00fcndelt die Landingpage einen \u00dcberblick \u00fcber Forschungsprojekte, Services und Veranstaltungen.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Mostafa, Malak\"\/>\n\t<meta name=\"keywords\" content=\"claix,claix-2023,claix-23,hochleistungsrechnen,hochleistungsrechner,hpc,hpc.nrw,informatik,nhr,nhr4ces,rwth-hpc,ank\u00fcndigungen,fun &amp; facts,hpcnews,insight it center,projekte &amp; kooperationen,services &amp; support\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/blog.rwth-aachen.de\/itc\/2024\/05\/15\/hpc-landingpage\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.8\" \/>\n\t\t<meta property=\"og:locale\" content=\"de_DE\" \/>\n\t\t<meta property=\"og:site_name\" content=\"IT Center Blog \u2022\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"HPC-Landingpage: Hochleistungsrechnen \u2022 IT Center Blog\" \/>\n\t\t<meta property=\"og:description\" content=\"Um f\u00fcr alle Nutzenden einen Einstiegspunkt f\u00fcr HPC zu schaffen, b\u00fcndelt die Landingpage einen \u00dcberblick \u00fcber Forschungsprojekte, Services und Veranstaltungen.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/blog.rwth-aachen.de\/itc\/2024\/05\/15\/hpc-landingpage\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-05-15T09:30:20+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-05-15T14:04:34+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/itcenterrwth\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@ITCenterRWTH\" \/>\n\t\t<meta name=\"twitter:title\" content=\"HPC-Landingpage: Hochleistungsrechnen \u2022 IT Center Blog\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Um f\u00fcr alle Nutzenden einen Einstiegspunkt f\u00fcr HPC zu schaffen, b\u00fcndelt die Landingpage einen \u00dcberblick \u00fcber Forschungsprojekte, Services und Veranstaltungen.\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@ITCenterRWTH\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/2024\\\/05\\\/15\\\/hpc-landingpage\\\/#blogposting\",\"name\":\"HPC-Landingpage: Hochleistungsrechnen \\u2022 IT Center Blog\",\"headline\":\"HPC-Landingpage: Hochleistungsrechnen\",\"author\":{\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/author\\\/5003\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/files\\\/2024\\\/05\\\/Bild1.jpg\",\"width\":1004,\"height\":565,\"caption\":\"Source: Own Illustration\"},\"datePublished\":\"2024-05-15T11:30:20+02:00\",\"dateModified\":\"2024-05-15T16:04:34+02:00\",\"inLanguage\":\"de-DE\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/2024\\\/05\\\/15\\\/hpc-landingpage\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/2024\\\/05\\\/15\\\/hpc-landingpage\\\/#webpage\"},\"articleSection\":\"Ank\\u00fcndigungen, Fun &amp; Facts, HPCnews, Insight IT Center, Projekte &amp; Kooperationen, Services &amp; Support, CLAIX, CLAIX-2023, CLAIX-23, Hochleistungsrechnen, Hochleistungsrechner, HPC, HPC.NRW, Informatik, NHR, NHR4CES, RWTH-HPC\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/2024\\\/05\\\/15\\\/hpc-landingpage\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/category\\\/themen\\\/#listItem\",\"name\":\"Themen\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/category\\\/themen\\\/#listItem\",\"position\":2,\"name\":\"Themen\",\"item\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/category\\\/themen\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/category\\\/themen\\\/ankuendigungen\\\/#listItem\",\"name\":\"Ank\\u00fcndigungen\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/category\\\/themen\\\/ankuendigungen\\\/#listItem\",\"position\":3,\"name\":\"Ank\\u00fcndigungen\",\"item\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/category\\\/themen\\\/ankuendigungen\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/2024\\\/05\\\/15\\\/hpc-landingpage\\\/#listItem\",\"name\":\"HPC-Landingpage: Hochleistungsrechnen\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/category\\\/themen\\\/#listItem\",\"name\":\"Themen\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/2024\\\/05\\\/15\\\/hpc-landingpage\\\/#listItem\",\"position\":4,\"name\":\"HPC-Landingpage: Hochleistungsrechnen\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/category\\\/themen\\\/ankuendigungen\\\/#listItem\",\"name\":\"Ank\\u00fcndigungen\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/#organization\",\"name\":\"IT Center RWTH Aachen University\",\"url\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/files\\\/2018\\\/09\\\/IT-Center-Logo.png\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/2024\\\/05\\\/15\\\/hpc-landingpage\\\/#organizationLogo\",\"width\":1312,\"height\":378,\"caption\":\"IT Center Logo\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/2024\\\/05\\\/15\\\/hpc-landingpage\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/itcenterrwth\",\"https:\\\/\\\/twitter.com\\\/ITCenterRWTH\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/itcenterrwthaachen\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/itcenterrwth\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/author\\\/5003\\\/#author\",\"url\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/author\\\/5003\\\/\",\"name\":\"Mostafa, Malak\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/2024\\\/05\\\/15\\\/hpc-landingpage\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ebc3fa9c50b86f358c82e24d178f4c6e2f5e049b725d3ca19fe370767c424b5?s=96&d=blank&r=g\",\"width\":96,\"height\":96,\"caption\":\"Mostafa, Malak\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/2024\\\/05\\\/15\\\/hpc-landingpage\\\/#webpage\",\"url\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/2024\\\/05\\\/15\\\/hpc-landingpage\\\/\",\"name\":\"HPC-Landingpage: Hochleistungsrechnen \\u2022 IT Center Blog\",\"description\":\"Um f\\u00fcr alle Nutzenden einen Einstiegspunkt f\\u00fcr HPC zu schaffen, b\\u00fcndelt die Landingpage einen \\u00dcberblick \\u00fcber Forschungsprojekte, Services und Veranstaltungen.\",\"inLanguage\":\"de-DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/2024\\\/05\\\/15\\\/hpc-landingpage\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/author\\\/5003\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/author\\\/5003\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/files\\\/2024\\\/05\\\/Bild1.jpg\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/2024\\\/05\\\/15\\\/hpc-landingpage\\\/#mainImage\",\"width\":1004,\"height\":565,\"caption\":\"Source: Own Illustration\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/2024\\\/05\\\/15\\\/hpc-landingpage\\\/#mainImage\"},\"datePublished\":\"2024-05-15T11:30:20+02:00\",\"dateModified\":\"2024-05-15T16:04:34+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/#website\",\"url\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/\",\"name\":\"IT Center Blog\",\"inLanguage\":\"de-DE\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"HPC-Landingpage: Hochleistungsrechnen \u2022 IT Center Blog","description":"Um f\u00fcr alle Nutzenden einen Einstiegspunkt f\u00fcr HPC zu schaffen, b\u00fcndelt die Landingpage einen \u00dcberblick \u00fcber Forschungsprojekte, Services und Veranstaltungen.","canonical_url":"https:\/\/blog.rwth-aachen.de\/itc\/2024\/05\/15\/hpc-landingpage\/","robots":"max-image-preview:large","keywords":"claix,claix-2023,claix-23,hochleistungsrechnen,hochleistungsrechner,hpc,hpc.nrw,informatik,nhr,nhr4ces,rwth-hpc,ank\u00fcndigungen,fun &amp; facts,hpcnews,insight it center,projekte &amp; kooperationen,services &amp; support","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/blog.rwth-aachen.de\/itc\/2024\/05\/15\/hpc-landingpage\/#blogposting","name":"HPC-Landingpage: Hochleistungsrechnen \u2022 IT Center Blog","headline":"HPC-Landingpage: Hochleistungsrechnen","author":{"@id":"https:\/\/blog.rwth-aachen.de\/itc\/author\/5003\/#author"},"publisher":{"@id":"https:\/\/blog.rwth-aachen.de\/itc\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/blog.rwth-aachen.de\/itc\/files\/2024\/05\/Bild1.jpg","width":1004,"height":565,"caption":"Source: Own Illustration"},"datePublished":"2024-05-15T11:30:20+02:00","dateModified":"2024-05-15T16:04:34+02:00","inLanguage":"de-DE","mainEntityOfPage":{"@id":"https:\/\/blog.rwth-aachen.de\/itc\/2024\/05\/15\/hpc-landingpage\/#webpage"},"isPartOf":{"@id":"https:\/\/blog.rwth-aachen.de\/itc\/2024\/05\/15\/hpc-landingpage\/#webpage"},"articleSection":"Ank\u00fcndigungen, Fun &amp; Facts, HPCnews, Insight IT Center, Projekte &amp; Kooperationen, Services &amp; Support, CLAIX, CLAIX-2023, CLAIX-23, Hochleistungsrechnen, Hochleistungsrechner, HPC, HPC.NRW, Informatik, NHR, NHR4CES, RWTH-HPC"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.rwth-aachen.de\/itc\/2024\/05\/15\/hpc-landingpage\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/blog.rwth-aachen.de\/itc#listItem","position":1,"name":"Home","item":"https:\/\/blog.rwth-aachen.de\/itc","nextItem":{"@type":"ListItem","@id":"https:\/\/blog.rwth-aachen.de\/itc\/category\/themen\/#listItem","name":"Themen"}},{"@type":"ListItem","@id":"https:\/\/blog.rwth-aachen.de\/itc\/category\/themen\/#listItem","position":2,"name":"Themen","item":"https:\/\/blog.rwth-aachen.de\/itc\/category\/themen\/","nextItem":{"@type":"ListItem","@id":"https:\/\/blog.rwth-aachen.de\/itc\/category\/themen\/ankuendigungen\/#listItem","name":"Ank\u00fcndigungen"},"previousItem":{"@type":"ListItem","@id":"https:\/\/blog.rwth-aachen.de\/itc#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/blog.rwth-aachen.de\/itc\/category\/themen\/ankuendigungen\/#listItem","position":3,"name":"Ank\u00fcndigungen","item":"https:\/\/blog.rwth-aachen.de\/itc\/category\/themen\/ankuendigungen\/","nextItem":{"@type":"ListItem","@id":"https:\/\/blog.rwth-aachen.de\/itc\/2024\/05\/15\/hpc-landingpage\/#listItem","name":"HPC-Landingpage: Hochleistungsrechnen"},"previousItem":{"@type":"ListItem","@id":"https:\/\/blog.rwth-aachen.de\/itc\/category\/themen\/#listItem","name":"Themen"}},{"@type":"ListItem","@id":"https:\/\/blog.rwth-aachen.de\/itc\/2024\/05\/15\/hpc-landingpage\/#listItem","position":4,"name":"HPC-Landingpage: Hochleistungsrechnen","previousItem":{"@type":"ListItem","@id":"https:\/\/blog.rwth-aachen.de\/itc\/category\/themen\/ankuendigungen\/#listItem","name":"Ank\u00fcndigungen"}}]},{"@type":"Organization","@id":"https:\/\/blog.rwth-aachen.de\/itc\/#organization","name":"IT Center RWTH Aachen University","url":"https:\/\/blog.rwth-aachen.de\/itc\/","logo":{"@type":"ImageObject","url":"https:\/\/blog.rwth-aachen.de\/itc\/files\/2018\/09\/IT-Center-Logo.png","@id":"https:\/\/blog.rwth-aachen.de\/itc\/2024\/05\/15\/hpc-landingpage\/#organizationLogo","width":1312,"height":378,"caption":"IT Center Logo"},"image":{"@id":"https:\/\/blog.rwth-aachen.de\/itc\/2024\/05\/15\/hpc-landingpage\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/itcenterrwth","https:\/\/twitter.com\/ITCenterRWTH","https:\/\/www.youtube.com\/c\/itcenterrwthaachen","https:\/\/www.linkedin.com\/company\/itcenterrwth"]},{"@type":"Person","@id":"https:\/\/blog.rwth-aachen.de\/itc\/author\/5003\/#author","url":"https:\/\/blog.rwth-aachen.de\/itc\/author\/5003\/","name":"Mostafa, Malak","image":{"@type":"ImageObject","@id":"https:\/\/blog.rwth-aachen.de\/itc\/2024\/05\/15\/hpc-landingpage\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/2ebc3fa9c50b86f358c82e24d178f4c6e2f5e049b725d3ca19fe370767c424b5?s=96&d=blank&r=g","width":96,"height":96,"caption":"Mostafa, Malak"}},{"@type":"WebPage","@id":"https:\/\/blog.rwth-aachen.de\/itc\/2024\/05\/15\/hpc-landingpage\/#webpage","url":"https:\/\/blog.rwth-aachen.de\/itc\/2024\/05\/15\/hpc-landingpage\/","name":"HPC-Landingpage: Hochleistungsrechnen \u2022 IT Center Blog","description":"Um f\u00fcr alle Nutzenden einen Einstiegspunkt f\u00fcr HPC zu schaffen, b\u00fcndelt die Landingpage einen \u00dcberblick \u00fcber Forschungsprojekte, Services und Veranstaltungen.","inLanguage":"de-DE","isPartOf":{"@id":"https:\/\/blog.rwth-aachen.de\/itc\/#website"},"breadcrumb":{"@id":"https:\/\/blog.rwth-aachen.de\/itc\/2024\/05\/15\/hpc-landingpage\/#breadcrumblist"},"author":{"@id":"https:\/\/blog.rwth-aachen.de\/itc\/author\/5003\/#author"},"creator":{"@id":"https:\/\/blog.rwth-aachen.de\/itc\/author\/5003\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/blog.rwth-aachen.de\/itc\/files\/2024\/05\/Bild1.jpg","@id":"https:\/\/blog.rwth-aachen.de\/itc\/2024\/05\/15\/hpc-landingpage\/#mainImage","width":1004,"height":565,"caption":"Source: Own Illustration"},"primaryImageOfPage":{"@id":"https:\/\/blog.rwth-aachen.de\/itc\/2024\/05\/15\/hpc-landingpage\/#mainImage"},"datePublished":"2024-05-15T11:30:20+02:00","dateModified":"2024-05-15T16:04:34+02:00"},{"@type":"WebSite","@id":"https:\/\/blog.rwth-aachen.de\/itc\/#website","url":"https:\/\/blog.rwth-aachen.de\/itc\/","name":"IT Center Blog","inLanguage":"de-DE","publisher":{"@id":"https:\/\/blog.rwth-aachen.de\/itc\/#organization"}}]},"og:locale":"de_DE","og:site_name":"IT Center Blog \u2022","og:type":"article","og:title":"HPC-Landingpage: Hochleistungsrechnen \u2022 IT Center Blog","og:description":"Um f\u00fcr alle Nutzenden einen Einstiegspunkt f\u00fcr HPC zu schaffen, b\u00fcndelt die Landingpage einen \u00dcberblick \u00fcber Forschungsprojekte, Services und Veranstaltungen.","og:url":"https:\/\/blog.rwth-aachen.de\/itc\/2024\/05\/15\/hpc-landingpage\/","article:published_time":"2024-05-15T09:30:20+00:00","article:modified_time":"2024-05-15T14:04:34+00:00","article:publisher":"https:\/\/www.facebook.com\/itcenterrwth","twitter:card":"summary","twitter:site":"@ITCenterRWTH","twitter:title":"HPC-Landingpage: Hochleistungsrechnen \u2022 IT Center Blog","twitter:description":"Um f\u00fcr alle Nutzenden einen Einstiegspunkt f\u00fcr HPC zu schaffen, b\u00fcndelt die Landingpage einen \u00dcberblick \u00fcber Forschungsprojekte, Services und Veranstaltungen.","twitter:creator":"@ITCenterRWTH"},"aioseo_meta_data":{"post_id":"19328","title":null,"description":"Um f\u00fcr alle Nutzenden einen Einstiegspunkt f\u00fcr HPC zu schaffen, b\u00fcndelt die Landingpage einen \u00dcberblick \u00fcber Forschungsprojekte, Services und Veranstaltungen.","keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2024-05-14 08:41:03","updated":"2025-07-08 14:37:30","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/blog.rwth-aachen.de\/itc\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/blog.rwth-aachen.de\/itc\/category\/themen\/\" title=\"Themen\">Themen<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/blog.rwth-aachen.de\/itc\/category\/themen\/ankuendigungen\/\" title=\"Ank\u00fcndigungen\">Ank\u00fcndigungen<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tHPC-Landingpage: Hochleistungsrechnen\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/blog.rwth-aachen.de\/itc"},{"label":"Themen","link":"https:\/\/blog.rwth-aachen.de\/itc\/category\/themen\/"},{"label":"Ank\u00fcndigungen","link":"https:\/\/blog.rwth-aachen.de\/itc\/category\/themen\/ankuendigungen\/"},{"label":"HPC-Landingpage: Hochleistungsrechnen","link":"https:\/\/blog.rwth-aachen.de\/itc\/2024\/05\/15\/hpc-landingpage\/"}],"_links":{"self":[{"href":"https:\/\/blog.rwth-aachen.de\/itc\/wp-json\/wp\/v2\/posts\/19328","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.rwth-aachen.de\/itc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.rwth-aachen.de\/itc\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.rwth-aachen.de\/itc\/wp-json\/wp\/v2\/users\/5003"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.rwth-aachen.de\/itc\/wp-json\/wp\/v2\/comments?post=19328"}],"version-history":[{"count":14,"href":"https:\/\/blog.rwth-aachen.de\/itc\/wp-json\/wp\/v2\/posts\/19328\/revisions"}],"predecessor-version":[{"id":19365,"href":"https:\/\/blog.rwth-aachen.de\/itc\/wp-json\/wp\/v2\/posts\/19328\/revisions\/19365"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.rwth-aachen.de\/itc\/wp-json\/wp\/v2\/media\/19329"}],"wp:attachment":[{"href":"https:\/\/blog.rwth-aachen.de\/itc\/wp-json\/wp\/v2\/media?parent=19328"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.rwth-aachen.de\/itc\/wp-json\/wp\/v2\/categories?post=19328"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.rwth-aachen.de\/itc\/wp-json\/wp\/v2\/tags?post=19328"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}