{"id":20929,"date":"2025-01-03T12:00:13","date_gmt":"2025-01-03T11:00:13","guid":{"rendered":"https:\/\/blog.rwth-aachen.de\/itc\/?p=20929"},"modified":"2025-01-08T08:34:44","modified_gmt":"2025-01-08T07:34:44","slug":"it-center-jahresruckblick-2024","status":"publish","type":"post","link":"https:\/\/blog.rwth-aachen.de\/itc\/2025\/01\/03\/it-center-jahresruckblick-2024\/","title":{"rendered":"Der IT Center Jahresr\u00fcckblick 2024"},"content":{"rendered":"<div class=\"twoclick_social_bookmarks_post_20929 social_share_privacy clearfix 1.6.4 locale-de_DE sprite-de_DE\"><\/div><div class=\"twoclick-js\"><script type=\"text\/javascript\">\/* <![CDATA[ *\/\njQuery(document).ready(function($){if($('.twoclick_social_bookmarks_post_20929')){$('.twoclick_social_bookmarks_post_20929').socialSharePrivacy({\"txt_help\":\"Wenn Sie diese Felder durch einen Klick aktivieren, werden Informationen an Facebook, Twitter, Flattr, Xing, t3n, LinkedIn, Pinterest oder Google eventuell ins Ausland \\u00fcbertragen und unter Umst\\u00e4nden auch dort gespeichert. N\\u00e4heres erfahren Sie durch einen Klick auf das <em>i<\\\/em>.\",\"settings_perma\":\"Dauerhaft aktivieren und Daten\\u00fcber-tragung zustimmen:\",\"info_link\":\"http:\\\/\\\/www.heise.de\\\/ct\\\/artikel\\\/2-Klicks-fuer-mehr-Datenschutz-1333879.html\",\"uri\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/2025\\\/01\\\/03\\\/it-center-jahresruckblick-2024\\\/\",\"post_id\":20929,\"post_title_referrer_track\":\"Der+IT+Center+Jahresr%C3%BCckblick+2024\",\"display_infobox\":\"on\"});}});\n\/* ]]> *\/<\/script><\/div><p><div id=\"attachment_20930\" style=\"width: 310px\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-20930\" class=\"size-medium wp-image-20930\" src=\"https:\/\/blog.rwth-aachen.de\/itc\/files\/2024\/12\/Blog-Layout-8-300x200.png\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/blog.rwth-aachen.de\/itc\/files\/2024\/12\/Blog-Layout-8-300x200.png 300w, https:\/\/blog.rwth-aachen.de\/itc\/files\/2024\/12\/Blog-Layout-8-1024x683.png 1024w, https:\/\/blog.rwth-aachen.de\/itc\/files\/2024\/12\/Blog-Layout-8-768x512.png 768w, https:\/\/blog.rwth-aachen.de\/itc\/files\/2024\/12\/Blog-Layout-8-1536x1024.png 1536w, https:\/\/blog.rwth-aachen.de\/itc\/files\/2024\/12\/Blog-Layout-8-2048x1365.png 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><p id=\"caption-attachment-20930\" class=\"wp-caption-text\">Quelle: <a href=\"https:\/\/de.freepik.com\/vektoren-kostenlos\/glueckliches-neues-jahr-2025-ereignis-hintergrunddesign_361060784.htm#fromView=search&amp;page=1&amp;position=16&amp;uuid=5f64c2df-0f02-4b72-8502-7a1957352054\">Freepik<\/a><\/p><\/div><\/p>\n<p>Das Jahr 2024 neigt sich dem Ende zu \u2013 ein Jahr voller spannender Projekte, erfolgreicher Kooperationen und unvergesslicher Momente am IT Center. Von innovativen Veranstaltungen und neuen Partnerschaften bis hin zu teaminternen Festlichkeiten und bedeutenden Ver\u00e4nderungen und neuen war das Jahr gepr\u00e4gt von Wachstum, Zusammenarbeit und gemeinsamer Weiterentwicklung. In unserem Jahresr\u00fcckblick werfen wir einen Blick auf die Highlights, die Ver\u00e4nderungen und die Erfolge, die unser Jahr so besonders gemacht haben.<\/p>\n<p>&nbsp;<\/p>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<h3><span style=\"color: #00549f;\">Wichtige Events und Kooperationen<\/span><\/h3>\n<p>Zu Beginn des Jahres hatten wir die Gelegenheit, uns mit zwei wichtigen Veranstaltungen zu pr\u00e4sentieren. Am 16. Februar waren wir Teil der <a href=\"https:\/\/blog.rwth-aachen.de\/itc\/2024\/03\/01\/ruckblick-auf-die-swt-messe-2024\/\">SWT-Messe<\/a>, bei der wir unsere Services und Projekte der IT-Interessierten der RWTH Aachen vorstellen konnten. Kurz darauf fand der <a href=\"https:\/\/blog.rwth-aachen.de\/itc\/2024\/03\/11\/rueckblick-vi-hps-porting-tuning-workshop-2024\/\">VI-HPS Porting &amp; Tuning Workshop<\/a> statt. Hier unterst\u00fctzten wir Entwickler*innen dabei, ihre Anwendungen f\u00fcr Hochleistungsrechner zu optimieren.<\/p>\n<p>Im M\u00e4rz ging es weiter mit dem <a href=\"https:\/\/blog.rwth-aachen.de\/itc\/2024\/04\/12\/ppces-im-fruehjahr-liegt-hpc-in-der-luft\/\">PPCES Workshop<\/a>, der vom 11. bis 15. M\u00e4rz den Fokus auf die Vermittlung von Grundlagen und fortgeschrittenen Themen der parallelen Programmierung und HPC-Codes legte. Am 10. April folgte das <a href=\"https:\/\/blog.rwth-aachen.de\/itc\/2024\/04\/17\/community-treffen-moodle-nrw\/\">Community-Treffen Moodle.NRW<\/a>. Das Treffen richtete sich an alle, die an ihrer Hochschule oder anderen Bildungseinrichtungen am Einsatz und der Entwicklung der Lernplattformen Moodle oder ILIAS beteiligt sind.<\/p>\n<p>Der Mai brachte auch die Ehre, bei der <a href=\"https:\/\/blog.rwth-aachen.de\/itc\/2024\/05\/29\/reinventing-hpc-it-centerisc24\/\">ISC24 Konferenz<\/a> mitzuwirken. Unter dem Motto \u201eReinventing HPC\u201c pr\u00e4sentierten wir in Hamburg die neuesten Entwicklungen in unsere HPC-Abteilung und trugen dazu bei, innovative Ans\u00e4tze im internationalen Kontext zu diskutieren.<\/p>\n<p>Wenige Wochen sp\u00e4ter, am 19. und 20. Juni, moderierten wir der <a href=\"https:\/\/blog.rwth-aachen.de\/itc\/2024\/06\/26\/aci-user-group-konferenz\/\">ACI User Group Konferenz<\/a>, die DataCenter-Netzwerkl\u00f6sung des IT Centers. Sie stellt die Netzwerkkonnektivit\u00e4t f\u00fcr mehr als 1.500 virtuelle Maschinen des IT Centers und seiner Kundschaft bereit.<\/p>\n<p>Auch der Sommer brachte internationale Highlights: Anfang August waren wir in Girona, Spanien bei der <a href=\"https:\/\/blog.rwth-aachen.de\/itc\/2024\/08\/05\/it-center-in-girona\/\">Customer Advisory Council (<\/a>CAC) vertreten. Ziel war es, den aktuellen Zufriedenheitsstand der Dell-Kundschaft zu ermitteln und mithilfe dieser Erkenntnisse Produkte und Dienstleistungen zu optimieren.<\/p>\n<p>Der Herbst hielt einen bedeutenden Meilenstein bereit: Am 23. Oktober wurde der <a href=\"https:\/\/blog.rwth-aachen.de\/itc\/2024\/10\/30\/claix-2023-2\/\">CLAIX-2023<\/a> Supercomputer offiziell in Betrieb genommen. Dieser wichtige Schritt in der Weiterentwicklung unserer HPC-Infrastruktur erm\u00f6glicht es, noch anspruchsvollere Forschungsprojekte zu unterst\u00fctzen. Mehrere Informationen findet ihr auch auf unserem <a href=\"https:\/\/youtu.be\/OShRJCk7VjI\">YouTube-Kanal<\/a>.<\/p>\n<p>&nbsp;<\/p>\n<h3><span style=\"color: #00549f;\">Ver\u00e4nderungen<\/span><\/h3>\n<p>Das Jahr 2024 brachte zahlreiche Neuerungen in den IT-Services der RWTH Aachen. Im Bereich der IT-Sicherheit wurde am 1. Februar die <a href=\"https:\/\/blog.rwth-aachen.de\/itc\/2024\/01\/24\/einfuehrung-vpn-mfa\/\">Multifaktor-Authentifizierung (MFA)<\/a> f\u00fcr den VPN-Zugang eingef\u00fchrt, um die Community besser vor unbefugtem Zugriff zu sch\u00fctzen. Ebenfalls im Februar gab es weitere Entwicklungen in unseren Services. Am 6. Februar wurde <a href=\"https:\/\/blog.rwth-aachen.de\/itc\/2024\/02\/07\/overleaf-im-regelbetrieb\/\">Overleaf<\/a> f\u00fcr Lehrende und Forschende in den Regelbetrieb \u00fcberf\u00fchrt, und ab dem 16. Februar wurde der <a href=\"https:\/\/blog.rwth-aachen.de\/itc\/2024\/02\/16\/ipv6-lizenzserver-software\/\">IPv6 Beta-Betrieb<\/a> bei Lizenzserver-Software unterst\u00fctzt, um die Effizienz bei der IT-Nutzung zu steigern.<\/p>\n<p>Am 23. Mai folgte der <a href=\"https:\/\/blog.rwth-aachen.de\/itc\/2024\/05\/24\/rwthmoodle-von-version-4-1-zu-4-3\/\">\u00dcbergang von RWTHmoodle auf Version 4.3<\/a> mit technischen Verbesserungen und benutzerfreundlichen Anleitungen. Auch die Pr\u00fcfungsverwaltung wurde durch das Plugin <a href=\"https:\/\/blog.rwth-aachen.de\/itc\/2024\/07\/08\/exam-scan\/\">Exam Scan<\/a> optimiert, das die Digitalisierung von Pr\u00fcfungsb\u00f6gen erm\u00f6glicht. Dar\u00fcber hinaus wurde die <a href=\"https:\/\/blog.rwth-aachen.de\/itc\/2024\/04\/24\/telefonverwaltung\/\">Telefonverwaltung<\/a> optimiert, was die Bearbeitung von Telefonanfragen erleichtert.<\/p>\n<p>Weitere Anpassungen waren die <a href=\"https:\/\/blog.rwth-aachen.de\/itc\/2024\/06\/07\/hpc-abschaltung-des-windows-frontends\/\">Abschaltung des Windows-Frontends<\/a> am 30. Juni zugunsten einer st\u00e4rkeren Fokussierung auf Unix-Systeme sowie die Entwicklung der <a href=\"https:\/\/blog.rwth-aachen.de\/itc\/2024\/05\/15\/hpc-landingpage\/\">HPC-Landingpage<\/a> zur verbesserten Zug\u00e4nglichkeit. Ein besonderes Highlight war die Einf\u00fchrung von <a href=\"https:\/\/blog.rwth-aachen.de\/itc\/2024\/08\/09\/neuer-meilenstein-erreicht-rwthgpt\/\">RWTHgpt<\/a> am 16. Juli, einem KI-gest\u00fctzten Service mit hohen Datenschutzstandards.<\/p>\n<p>Des Weiteren wurde die <a href=\"https:\/\/blog.rwth-aachen.de\/itc\/2024\/08\/02\/tremoge-euer-zentraler-anker\/\">TreMoGe-Plattform<\/a> weiter ausgebaut, um Studierenden und Mitarbeitenden bei mobilen Endger\u00e4ten zu unterst\u00fctzen. Au\u00dferdem wurde die <a href=\"https:\/\/blog.rwth-aachen.de\/itc\/2024\/10\/28\/e-mail-6\/\">E-Mail-Verwaltung<\/a> ab dem 28. November optimiert, um den steigenden Anforderungen gerecht zu werden und die Nutzererfahrung zu verbessern.<\/p>\n<p>Diese Ver\u00e4nderungen unterstreichen das Ziel des IT Centers, die RWTH Aachen mit innovativen L\u00f6sungen zukunftssicher zu machen und den Anforderungen der digitalen Welt gerecht zu werden.<\/p>\n<p>&nbsp;<\/p>\n<h3><span style=\"color: #00549f;\">Festivit\u00e4ten<\/span><\/h3>\n<p>In diesem Jahr konnten wir wieder unsere gewohnten Festivit\u00e4ten feiern, darunter die <a href=\"https:\/\/blog.rwth-aachen.de\/itc\/2024\/02\/19\/karnevalsfeier-am-it-center-2024\/\">Karnevalsfeier,<\/a> den <a href=\"https:\/\/blog.rwth-aachen.de\/itc\/2024\/04\/26\/betriebsausflug-2024-koeln-wir-kommen\/\">Betriebsausflug,<\/a> das <a href=\"https:\/\/blog.rwth-aachen.de\/itc\/2024\/06\/28\/sommerfest-2024\/\">Sommerfest,<\/a> das traditionelle <a href=\"https:\/\/blog.rwth-aachen.de\/itc\/2024\/10\/09\/it-center-oktoberfest-2024\/\">Oktoberfest<\/a> und die Weihnachtsfeier. Alle diese Veranstaltungen waren ein gro\u00dfer Erfolg und trugen dazu bei, das Team weiter zu st\u00e4rken.<\/p>\n<p>&nbsp;<\/p>\n<h3><span style=\"color: #00549f;\">Gr\u00fcnde zu feiern<\/span><\/h3>\n<p>Im Jahr 2024 blickte das IT Center auf zahlreiche Erfolge zur\u00fcck, die das Engagement seiner Mitarbeitenden und Auszubildenden unterstreichen.<\/p>\n<p>Bereits zu Beginn des Jahres erhielt Yasin Kalem, ein Auszubildender des IT Centers, eine <a href=\"https:\/\/blog.rwth-aachen.de\/itc\/2024\/01\/12\/auszubildender-am-it-center-erhaelt-auszeichnung-fuer-auslandspraktikum\/\">besondere Auszeichnung f\u00fcr ein herausragend absolviertes Auslandspraktikum<\/a> \u2013 ein inspirierender Moment, der die Qualit\u00e4t der Ausbildung am IT Center bekr\u00e4ftigte.<\/p>\n<p>Im Februar feierten wir den Start des \u201eRhein-Ruhr Zentrums f\u00fcr wissenschaftliche Datenkompetenz\u201d (<a href=\"https:\/\/blog.rwth-aachen.de\/itc\/2024\/02\/21\/das-dkz-2r-ist-gestartet\/\">DKZ.2R<\/a>) einen wichtigen Schritt in der Weiterentwicklung unserer Infrastruktur. Ziel ist es, Forschende zu unterst\u00fctzen und ihre Kompetenz in Data Science, HPC, FDM und Machine Learning auszubauen.<\/p>\n<p>Ein weiteres Jubil\u00e4um konnte am 5. M\u00e4rz begangen werden: <a href=\"https:\/\/blog.rwth-aachen.de\/itc\/2024\/03\/25\/5-jahre-rwthmoodle\/\">F\u00fcnf Jahre RWTHmoodle<\/a>! Seit seiner Einf\u00fchrung hat sich die Plattform als unverzichtbares Werkzeug f\u00fcr digitale Lehre etabliert und feiert einen stetigen Nutzerzuwachs.<\/p>\n<p>Der 26. Juli stand ganz im Zeichen des <a href=\"https:\/\/blog.rwth-aachen.de\/itc\/2024\/07\/26\/sysadmin-day-2024-wir-sagen-danke\/\">SysAdmin Day 2024<\/a>, bei dem wir den Einsatz und die Expertise unserer Mitarbeitenden w\u00fcrdigten, die t\u00e4glich daf\u00fcr sorgen, dass unsere IT-Systeme reibungslos laufen.<\/p>\n<p>Auch unser Engagement in der Lehre war ein Grund zur Freude: Am 3. September hie\u00df das MATSE-Programm 103 <a href=\"https:\/\/blog.rwth-aachen.de\/itc\/2024\/09\/13\/willkommen-103-matse-azubis\/\">neue Auszubildende<\/a> willkommen und feierte am 9. September die erfolgreichen <a href=\"https:\/\/blog.rwth-aachen.de\/itc\/2024\/09\/27\/herzlichen-glueckwunsch-liebe-matse-absolventinnen\/\">MATSE-Absolvent*innen<\/a>, die ihre Ausbildung mit Bravour abgeschlossen haben.<\/p>\n<p>Unser HPC-Team feierte im September gleich zwei gro\u00dfe Erfolge: <a href=\"https:\/\/www.itc.rwth-aachen.de\/cms\/it-center\/it-center\/profil\/team\/~epvp\/mitarbeiter-campus-\/?gguid=PER-SLGXZNP&amp;allou=1\">Semih Burak<\/a> gewann den Rusty Lusk Award auf der EuroMPI\/Australia 2024 f\u00fcr sein <a href=\"https:\/\/link.springer.com\/chapter\/10.1007\/978-3-031-73370-3_1\">Paper<\/a>. <a href=\"https:\/\/www.itc.rwth-aachen.de\/go\/id\/epvp\/gguid\/PER-PLDTKW3\/allou\/1\/\">Jannis Klinkenberg<\/a> sicherte sich f\u00fcr seinen <a href=\"https:\/\/link.springer.com\/chapter\/10.1007\/978-3-031-72567-8_1\">Konferenzbeitrag<\/a> den Best Paper Award auf dem IWOMP 2024. Beide Veranstaltungen sind bedeutend f\u00fcr parallele Programmierparadigmen wie MPI und OpenMP, die in der HPC-Welt eine zentrale Rolle spielen.<\/p>\n<p>Au\u00dferdem feierten wir im November 2024 einen wichtigen Meilenstein: die erfolgreiche <a href=\"https:\/\/blog.rwth-aachen.de\/itc\/2024\/11\/27\/coscine-markenanmeldung\/\">Markenanmeldung von Coscine<\/a>, einer Innovation, die die Forschungsdatenverwaltung st\u00e4rkt und die internationale Zusammenarbeit der RWTH Aachen f\u00f6rdert.<\/p>\n<p>Dank dieser wichtigen Ereignisse und Erfolge wird das Jahr 2024 ein herausragendes Kapitel in der Geschichte des IT Centers der RWTH Aachen bleiben. Wir hoffen, dass das neue Jahr genauso reich an erf\u00fcllenden Momenten, Erfolgen und kollektiven Errungenschaften sein wird.<\/p>\n<p>&nbsp;<\/p>\n<hr \/>\n<p>Verantwortlich f\u00fcr die Inhalte dieses Beitrags sind <a href=\"https:\/\/www.itc.rwth-aachen.de\/cms\/it-center\/it-center\/profil\/team\/~epvp\/mitarbeiter-campus-\/?gguid=PER-DTJF9WU&amp;allou=1\">Hania Eid<\/a> und <a href=\"https:\/\/www.itc.rwth-aachen.de\/cms\/it-center\/it-center\/profil\/team\/~epvp\/mitarbeiter-campus-\/?gguid=PER-FSX9U9J&amp;allou=1\">Malak Mostafa<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Das Jahr 2024 neigt sich dem Ende zu \u2013 ein Jahr voller spannender Projekte, erfolgreicher Kooperationen und unvergesslicher Momente am IT Center. Von innovativen Veranstaltungen und neuen Partnerschaften bis hin [&hellip;]<\/p>\n","protected":false},"author":5003,"featured_media":20930,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"c2c_always_allow_admin_comments":false,"footnotes":""},"categories":[308,311,312,316,315],"tags":[1363,256,1365,153,724,1364],"class_list":["post-20929","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-events-jubilaen-erfolge","category-fun-facts","category-insight-it-center","category-projekte-kooperationen","category-services-support","tag-erfolge","tag-events","tag-festivitaten","tag-jahresrueckblick","tag-neujahr","tag-veranderungen"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.8 - aioseo.com -->\n\t<meta name=\"description\" content=\"In unserem Jahresr\u00fcckblick werfen wir einen Blick auf die Highlights, die Ver\u00e4nderungen und die Erfolge, die unser Jahr so besonders gemacht haben.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Mostafa, Malak\"\/>\n\t<meta name=\"keywords\" content=\"erfolge,events,festivit\u00e4ten,jahresr\u00fcckblick,neujahr,ver\u00e4nderungen,events, jubil\u00e4en &amp; erfolge,fun &amp; facts,insight it center,projekte &amp; kooperationen,services &amp; support\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/blog.rwth-aachen.de\/itc\/2025\/01\/03\/it-center-jahresruckblick-2024\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.8\" \/>\n\t\t<meta property=\"og:locale\" content=\"de_DE\" \/>\n\t\t<meta property=\"og:site_name\" content=\"IT Center Blog \u2022\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Der IT Center Jahresr\u00fcckblick 2024 \u2022 IT Center Blog\" \/>\n\t\t<meta property=\"og:description\" content=\"In unserem Jahresr\u00fcckblick werfen wir einen Blick auf die Highlights, die Ver\u00e4nderungen und die Erfolge, die unser Jahr so besonders gemacht haben.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/blog.rwth-aachen.de\/itc\/2025\/01\/03\/it-center-jahresruckblick-2024\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2025-01-03T11:00:13+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-01-08T07:34:44+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/itcenterrwth\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@ITCenterRWTH\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Der IT Center Jahresr\u00fcckblick 2024 \u2022 IT Center Blog\" \/>\n\t\t<meta name=\"twitter:description\" content=\"In unserem Jahresr\u00fcckblick werfen wir einen Blick auf die Highlights, die Ver\u00e4nderungen und die Erfolge, die unser Jahr so besonders gemacht haben.\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@ITCenterRWTH\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/2025\\\/01\\\/03\\\/it-center-jahresruckblick-2024\\\/#blogposting\",\"name\":\"Der IT Center Jahresr\\u00fcckblick 2024 \\u2022 IT Center Blog\",\"headline\":\"Der IT Center Jahresr\\u00fcckblick 2024\",\"author\":{\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/author\\\/5003\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/files\\\/2024\\\/12\\\/Blog-Layout-8.png\",\"width\":3000,\"height\":2000,\"caption\":\"Source: Freepik\"},\"datePublished\":\"2025-01-03T12:00:13+01:00\",\"dateModified\":\"2025-01-08T08:34:44+01:00\",\"inLanguage\":\"de-DE\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/2025\\\/01\\\/03\\\/it-center-jahresruckblick-2024\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/2025\\\/01\\\/03\\\/it-center-jahresruckblick-2024\\\/#webpage\"},\"articleSection\":\"Events, Jubil\\u00e4en &amp; Erfolge, Fun &amp; Facts, Insight IT Center, Projekte &amp; Kooperationen, Services &amp; Support, Erfolge, Events, Festivit\\u00e4ten, Jahresr\\u00fcckblick, Neujahr, Ver\\u00e4nderungen\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/2025\\\/01\\\/03\\\/it-center-jahresruckblick-2024\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/category\\\/themen\\\/#listItem\",\"name\":\"Themen\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/category\\\/themen\\\/#listItem\",\"position\":2,\"name\":\"Themen\",\"item\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/category\\\/themen\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/category\\\/themen\\\/events-jubilaen-erfolge\\\/#listItem\",\"name\":\"Events, Jubil\\u00e4en &amp; Erfolge\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/category\\\/themen\\\/events-jubilaen-erfolge\\\/#listItem\",\"position\":3,\"name\":\"Events, Jubil\\u00e4en &amp; Erfolge\",\"item\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/category\\\/themen\\\/events-jubilaen-erfolge\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/2025\\\/01\\\/03\\\/it-center-jahresruckblick-2024\\\/#listItem\",\"name\":\"Der IT Center Jahresr\\u00fcckblick 2024\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/category\\\/themen\\\/#listItem\",\"name\":\"Themen\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/2025\\\/01\\\/03\\\/it-center-jahresruckblick-2024\\\/#listItem\",\"position\":4,\"name\":\"Der IT Center Jahresr\\u00fcckblick 2024\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/category\\\/themen\\\/events-jubilaen-erfolge\\\/#listItem\",\"name\":\"Events, Jubil\\u00e4en &amp; Erfolge\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/#organization\",\"name\":\"IT Center RWTH Aachen University\",\"url\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/files\\\/2018\\\/09\\\/IT-Center-Logo.png\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/2025\\\/01\\\/03\\\/it-center-jahresruckblick-2024\\\/#organizationLogo\",\"width\":1312,\"height\":378,\"caption\":\"IT Center Logo\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/2025\\\/01\\\/03\\\/it-center-jahresruckblick-2024\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/itcenterrwth\",\"https:\\\/\\\/twitter.com\\\/ITCenterRWTH\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/itcenterrwthaachen\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/itcenterrwth\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/author\\\/5003\\\/#author\",\"url\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/author\\\/5003\\\/\",\"name\":\"Mostafa, Malak\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/2025\\\/01\\\/03\\\/it-center-jahresruckblick-2024\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ebc3fa9c50b86f358c82e24d178f4c6e2f5e049b725d3ca19fe370767c424b5?s=96&d=blank&r=g\",\"width\":96,\"height\":96,\"caption\":\"Mostafa, Malak\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/2025\\\/01\\\/03\\\/it-center-jahresruckblick-2024\\\/#webpage\",\"url\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/2025\\\/01\\\/03\\\/it-center-jahresruckblick-2024\\\/\",\"name\":\"Der IT Center Jahresr\\u00fcckblick 2024 \\u2022 IT Center Blog\",\"description\":\"In unserem Jahresr\\u00fcckblick werfen wir einen Blick auf die Highlights, die Ver\\u00e4nderungen und die Erfolge, die unser Jahr so besonders gemacht haben.\",\"inLanguage\":\"de-DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/2025\\\/01\\\/03\\\/it-center-jahresruckblick-2024\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/author\\\/5003\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/author\\\/5003\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/files\\\/2024\\\/12\\\/Blog-Layout-8.png\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/2025\\\/01\\\/03\\\/it-center-jahresruckblick-2024\\\/#mainImage\",\"width\":3000,\"height\":2000,\"caption\":\"Source: Freepik\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/2025\\\/01\\\/03\\\/it-center-jahresruckblick-2024\\\/#mainImage\"},\"datePublished\":\"2025-01-03T12:00:13+01:00\",\"dateModified\":\"2025-01-08T08:34:44+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/#website\",\"url\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/\",\"name\":\"IT Center Blog\",\"inLanguage\":\"de-DE\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Der IT Center Jahresr\u00fcckblick 2024 \u2022 IT Center Blog","description":"In unserem Jahresr\u00fcckblick werfen wir einen Blick auf die Highlights, die Ver\u00e4nderungen und die Erfolge, die unser Jahr so besonders gemacht haben.","canonical_url":"https:\/\/blog.rwth-aachen.de\/itc\/2025\/01\/03\/it-center-jahresruckblick-2024\/","robots":"max-image-preview:large","keywords":"erfolge,events,festivit\u00e4ten,jahresr\u00fcckblick,neujahr,ver\u00e4nderungen,events, jubil\u00e4en &amp; erfolge,fun &amp; facts,insight it center,projekte &amp; kooperationen,services &amp; support","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/blog.rwth-aachen.de\/itc\/2025\/01\/03\/it-center-jahresruckblick-2024\/#blogposting","name":"Der IT Center Jahresr\u00fcckblick 2024 \u2022 IT Center Blog","headline":"Der IT Center Jahresr\u00fcckblick 2024","author":{"@id":"https:\/\/blog.rwth-aachen.de\/itc\/author\/5003\/#author"},"publisher":{"@id":"https:\/\/blog.rwth-aachen.de\/itc\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/blog.rwth-aachen.de\/itc\/files\/2024\/12\/Blog-Layout-8.png","width":3000,"height":2000,"caption":"Source: Freepik"},"datePublished":"2025-01-03T12:00:13+01:00","dateModified":"2025-01-08T08:34:44+01:00","inLanguage":"de-DE","mainEntityOfPage":{"@id":"https:\/\/blog.rwth-aachen.de\/itc\/2025\/01\/03\/it-center-jahresruckblick-2024\/#webpage"},"isPartOf":{"@id":"https:\/\/blog.rwth-aachen.de\/itc\/2025\/01\/03\/it-center-jahresruckblick-2024\/#webpage"},"articleSection":"Events, Jubil\u00e4en &amp; Erfolge, Fun &amp; Facts, Insight IT Center, Projekte &amp; Kooperationen, Services &amp; Support, Erfolge, Events, Festivit\u00e4ten, Jahresr\u00fcckblick, Neujahr, Ver\u00e4nderungen"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.rwth-aachen.de\/itc\/2025\/01\/03\/it-center-jahresruckblick-2024\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/blog.rwth-aachen.de\/itc#listItem","position":1,"name":"Home","item":"https:\/\/blog.rwth-aachen.de\/itc","nextItem":{"@type":"ListItem","@id":"https:\/\/blog.rwth-aachen.de\/itc\/category\/themen\/#listItem","name":"Themen"}},{"@type":"ListItem","@id":"https:\/\/blog.rwth-aachen.de\/itc\/category\/themen\/#listItem","position":2,"name":"Themen","item":"https:\/\/blog.rwth-aachen.de\/itc\/category\/themen\/","nextItem":{"@type":"ListItem","@id":"https:\/\/blog.rwth-aachen.de\/itc\/category\/themen\/events-jubilaen-erfolge\/#listItem","name":"Events, Jubil\u00e4en &amp; Erfolge"},"previousItem":{"@type":"ListItem","@id":"https:\/\/blog.rwth-aachen.de\/itc#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/blog.rwth-aachen.de\/itc\/category\/themen\/events-jubilaen-erfolge\/#listItem","position":3,"name":"Events, Jubil\u00e4en &amp; Erfolge","item":"https:\/\/blog.rwth-aachen.de\/itc\/category\/themen\/events-jubilaen-erfolge\/","nextItem":{"@type":"ListItem","@id":"https:\/\/blog.rwth-aachen.de\/itc\/2025\/01\/03\/it-center-jahresruckblick-2024\/#listItem","name":"Der IT Center Jahresr\u00fcckblick 2024"},"previousItem":{"@type":"ListItem","@id":"https:\/\/blog.rwth-aachen.de\/itc\/category\/themen\/#listItem","name":"Themen"}},{"@type":"ListItem","@id":"https:\/\/blog.rwth-aachen.de\/itc\/2025\/01\/03\/it-center-jahresruckblick-2024\/#listItem","position":4,"name":"Der IT Center Jahresr\u00fcckblick 2024","previousItem":{"@type":"ListItem","@id":"https:\/\/blog.rwth-aachen.de\/itc\/category\/themen\/events-jubilaen-erfolge\/#listItem","name":"Events, Jubil\u00e4en &amp; Erfolge"}}]},{"@type":"Organization","@id":"https:\/\/blog.rwth-aachen.de\/itc\/#organization","name":"IT Center RWTH Aachen University","url":"https:\/\/blog.rwth-aachen.de\/itc\/","logo":{"@type":"ImageObject","url":"https:\/\/blog.rwth-aachen.de\/itc\/files\/2018\/09\/IT-Center-Logo.png","@id":"https:\/\/blog.rwth-aachen.de\/itc\/2025\/01\/03\/it-center-jahresruckblick-2024\/#organizationLogo","width":1312,"height":378,"caption":"IT Center Logo"},"image":{"@id":"https:\/\/blog.rwth-aachen.de\/itc\/2025\/01\/03\/it-center-jahresruckblick-2024\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/itcenterrwth","https:\/\/twitter.com\/ITCenterRWTH","https:\/\/www.youtube.com\/c\/itcenterrwthaachen","https:\/\/www.linkedin.com\/company\/itcenterrwth"]},{"@type":"Person","@id":"https:\/\/blog.rwth-aachen.de\/itc\/author\/5003\/#author","url":"https:\/\/blog.rwth-aachen.de\/itc\/author\/5003\/","name":"Mostafa, Malak","image":{"@type":"ImageObject","@id":"https:\/\/blog.rwth-aachen.de\/itc\/2025\/01\/03\/it-center-jahresruckblick-2024\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/2ebc3fa9c50b86f358c82e24d178f4c6e2f5e049b725d3ca19fe370767c424b5?s=96&d=blank&r=g","width":96,"height":96,"caption":"Mostafa, Malak"}},{"@type":"WebPage","@id":"https:\/\/blog.rwth-aachen.de\/itc\/2025\/01\/03\/it-center-jahresruckblick-2024\/#webpage","url":"https:\/\/blog.rwth-aachen.de\/itc\/2025\/01\/03\/it-center-jahresruckblick-2024\/","name":"Der IT Center Jahresr\u00fcckblick 2024 \u2022 IT Center Blog","description":"In unserem Jahresr\u00fcckblick werfen wir einen Blick auf die Highlights, die Ver\u00e4nderungen und die Erfolge, die unser Jahr so besonders gemacht haben.","inLanguage":"de-DE","isPartOf":{"@id":"https:\/\/blog.rwth-aachen.de\/itc\/#website"},"breadcrumb":{"@id":"https:\/\/blog.rwth-aachen.de\/itc\/2025\/01\/03\/it-center-jahresruckblick-2024\/#breadcrumblist"},"author":{"@id":"https:\/\/blog.rwth-aachen.de\/itc\/author\/5003\/#author"},"creator":{"@id":"https:\/\/blog.rwth-aachen.de\/itc\/author\/5003\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/blog.rwth-aachen.de\/itc\/files\/2024\/12\/Blog-Layout-8.png","@id":"https:\/\/blog.rwth-aachen.de\/itc\/2025\/01\/03\/it-center-jahresruckblick-2024\/#mainImage","width":3000,"height":2000,"caption":"Source: Freepik"},"primaryImageOfPage":{"@id":"https:\/\/blog.rwth-aachen.de\/itc\/2025\/01\/03\/it-center-jahresruckblick-2024\/#mainImage"},"datePublished":"2025-01-03T12:00:13+01:00","dateModified":"2025-01-08T08:34:44+01:00"},{"@type":"WebSite","@id":"https:\/\/blog.rwth-aachen.de\/itc\/#website","url":"https:\/\/blog.rwth-aachen.de\/itc\/","name":"IT Center Blog","inLanguage":"de-DE","publisher":{"@id":"https:\/\/blog.rwth-aachen.de\/itc\/#organization"}}]},"og:locale":"de_DE","og:site_name":"IT Center Blog \u2022","og:type":"article","og:title":"Der IT Center Jahresr\u00fcckblick 2024 \u2022 IT Center Blog","og:description":"In unserem Jahresr\u00fcckblick werfen wir einen Blick auf die Highlights, die Ver\u00e4nderungen und die Erfolge, die unser Jahr so besonders gemacht haben.","og:url":"https:\/\/blog.rwth-aachen.de\/itc\/2025\/01\/03\/it-center-jahresruckblick-2024\/","article:published_time":"2025-01-03T11:00:13+00:00","article:modified_time":"2025-01-08T07:34:44+00:00","article:publisher":"https:\/\/www.facebook.com\/itcenterrwth","twitter:card":"summary","twitter:site":"@ITCenterRWTH","twitter:title":"Der IT Center Jahresr\u00fcckblick 2024 \u2022 IT Center Blog","twitter:description":"In unserem Jahresr\u00fcckblick werfen wir einen Blick auf die Highlights, die Ver\u00e4nderungen und die Erfolge, die unser Jahr so besonders gemacht haben.","twitter:creator":"@ITCenterRWTH"},"aioseo_meta_data":{"post_id":"20929","title":null,"description":"In unserem Jahresr\u00fcckblick werfen wir einen Blick auf die Highlights, die Ver\u00e4nderungen und die Erfolge, die unser Jahr so besonders gemacht haben.","keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2024-12-06 11:00:20","updated":"2025-07-08 14:49:01","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/blog.rwth-aachen.de\/itc\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/blog.rwth-aachen.de\/itc\/category\/themen\/\" title=\"Themen\">Themen<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/blog.rwth-aachen.de\/itc\/category\/themen\/events-jubilaen-erfolge\/\" title=\"Events, Jubil\u00e4en &amp; Erfolge\">Events, Jubil\u00e4en &amp; Erfolge<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tDer IT Center Jahresr\u00fcckblick 2024\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/blog.rwth-aachen.de\/itc"},{"label":"Themen","link":"https:\/\/blog.rwth-aachen.de\/itc\/category\/themen\/"},{"label":"Events, Jubil\u00e4en &amp; Erfolge","link":"https:\/\/blog.rwth-aachen.de\/itc\/category\/themen\/events-jubilaen-erfolge\/"},{"label":"Der IT Center Jahresr\u00fcckblick 2024","link":"https:\/\/blog.rwth-aachen.de\/itc\/2025\/01\/03\/it-center-jahresruckblick-2024\/"}],"_links":{"self":[{"href":"https:\/\/blog.rwth-aachen.de\/itc\/wp-json\/wp\/v2\/posts\/20929","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.rwth-aachen.de\/itc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.rwth-aachen.de\/itc\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.rwth-aachen.de\/itc\/wp-json\/wp\/v2\/users\/5003"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.rwth-aachen.de\/itc\/wp-json\/wp\/v2\/comments?post=20929"}],"version-history":[{"count":7,"href":"https:\/\/blog.rwth-aachen.de\/itc\/wp-json\/wp\/v2\/posts\/20929\/revisions"}],"predecessor-version":[{"id":21069,"href":"https:\/\/blog.rwth-aachen.de\/itc\/wp-json\/wp\/v2\/posts\/20929\/revisions\/21069"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.rwth-aachen.de\/itc\/wp-json\/wp\/v2\/media\/20930"}],"wp:attachment":[{"href":"https:\/\/blog.rwth-aachen.de\/itc\/wp-json\/wp\/v2\/media?parent=20929"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.rwth-aachen.de\/itc\/wp-json\/wp\/v2\/categories?post=20929"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.rwth-aachen.de\/itc\/wp-json\/wp\/v2\/tags?post=20929"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}