{"id":23291,"date":"2025-11-24T12:00:37","date_gmt":"2025-11-24T11:00:37","guid":{"rendered":"https:\/\/blog.rwth-aachen.de\/itc\/?p=23291"},"modified":"2025-11-21T12:33:17","modified_gmt":"2025-11-21T11:33:17","slug":"ritchy-umfrage","status":"publish","type":"post","link":"https:\/\/blog.rwth-aachen.de\/itc\/2025\/11\/24\/ritchy-umfrage\/","title":{"rendered":"Ritchy \u2013 Eure Meinung z\u00e4hlt!"},"content":{"rendered":"<div class=\"twoclick_social_bookmarks_post_23291 social_share_privacy clearfix 1.6.4 locale-de_DE sprite-de_DE\"><\/div><div class=\"twoclick-js\"><script type=\"text\/javascript\">\/* <![CDATA[ *\/\njQuery(document).ready(function($){if($('.twoclick_social_bookmarks_post_23291')){$('.twoclick_social_bookmarks_post_23291').socialSharePrivacy({\"txt_help\":\"Wenn Sie diese Felder durch einen Klick aktivieren, werden Informationen an Facebook, Twitter, Flattr, Xing, t3n, LinkedIn, Pinterest oder Google eventuell ins Ausland \\u00fcbertragen und unter Umst\\u00e4nden auch dort gespeichert. N\\u00e4heres erfahren Sie durch einen Klick auf das <em>i<\\\/em>.\",\"settings_perma\":\"Dauerhaft aktivieren und Daten\\u00fcber-tragung zustimmen:\",\"info_link\":\"http:\\\/\\\/www.heise.de\\\/ct\\\/artikel\\\/2-Klicks-fuer-mehr-Datenschutz-1333879.html\",\"uri\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/2025\\\/11\\\/24\\\/ritchy-umfrage\\\/\",\"post_id\":23291,\"post_title_referrer_track\":\"Ritchy+%E2%80%93+Eure+Meinung+z%C3%A4hlt%21\",\"display_infobox\":\"on\"});}});\n\/* ]]> *\/<\/script><\/div><p><div id=\"attachment_22887\" style=\"width: 310px\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-22887\" class=\"wp-image-22887 size-medium\" src=\"https:\/\/blog.rwth-aachen.de\/itc\/files\/2025\/09\/Ritchy_20250919_BAU_Blog-300x200.png\" alt=\"Kopf eines Waschb\u00e4rs\" width=\"300\" height=\"200\" srcset=\"https:\/\/blog.rwth-aachen.de\/itc\/files\/2025\/09\/Ritchy_20250919_BAU_Blog-300x200.png 300w, https:\/\/blog.rwth-aachen.de\/itc\/files\/2025\/09\/Ritchy_20250919_BAU_Blog-1024x683.png 1024w, https:\/\/blog.rwth-aachen.de\/itc\/files\/2025\/09\/Ritchy_20250919_BAU_Blog-768x512.png 768w, https:\/\/blog.rwth-aachen.de\/itc\/files\/2025\/09\/Ritchy_20250919_BAU_Blog.png 1500w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><p id=\"caption-attachment-22887\" class=\"wp-caption-text\">Quelle: Eigene Darstellung<\/p><\/div><\/p>\n<p>Seit April 2025 unterst\u00fctzt euch unser <a href=\"https:\/\/ritchy.itc.rwth-aachen.de\/\">Chatbot Ritchy<\/a> rund um die Uhr &#8211; auch au\u00dferhalb unserer <a href=\"https:\/\/help.itc.rwth-aachen.de\/service\/b734502cd73e4201b1f763a65a61bf9c\/article\/cbf1b80232b34626bbd53dda48578c09\/\">regul\u00e4ren Supportzeiten<\/a>. Er steht euch mit Antworten, Tipps und L\u00f6sungsvorschl\u00e4gen zur Seite und soll den pers\u00f6nlichen Kundensupport optimal erg\u00e4nzen.<\/p>\n<p>Wir haben Ritchy bereits in einem fr\u00fcheren <a href=\"https:\/\/blog.rwth-aachen.de\/itc\/2025\/09\/22\/ritchy\/\">Blogbeitrag<\/a> vorgestellt und erkl\u00e4rt, welche Vorteile und Besonderheiten er mit sich bringt.<br \/>\nFalls ihr mehr \u00fcber unseren Chatbot erfahren m\u00f6chtet, lohnt sich ein Blick in diesen Beitrag unbedingt.<\/p>\n<p>&nbsp;<\/p>\n<p><!--more--><\/p>\n<h3><span style=\"color: #00549f;\"><strong>Eure Meinung ist uns wichtig<\/strong><\/span><\/h3>\n<p>Neben dem integrierten Feedbacksystem, bei dem ihr jede Antwort mit einem Daumen hoch oder runter bewerten k\u00f6nnt, m\u00f6chten wir nun erstmals die Akzeptanz und Nutzungsbereitschaft des Chatbots gezielt messen. Unser Ziel: Ritchy noch besser an eure Bed\u00fcrfnisse anzupassen &#8211; daf\u00fcr brauchen wir eure Unterst\u00fctzung!<\/p>\n<p>&nbsp;<\/p>\n<h3><span style=\"color: #00549f;\"><strong>So k\u00f6nnt ihr teilnehmen<\/strong><\/span><\/h3>\n<p>Wenn ihr Ritchy schon einmal verwendet habt, dann laden wir euch ein, an unserer <a href=\"https:\/\/www.itc.rwth-aachen.de\/ritchy-umfrage\">Umfrage<\/a> teilzunehmen. Die Umfrage l\u00e4uft vom 19. November 2025 bis zum 18. Januar 2026.<\/p>\n<p>Die Erhebung ist selbstverst\u00e4ndlich anonym, nimmt nur etwa 10 Minuten in Anspruch und kann in deutscher oder englischer Sprache ausgef\u00fcllt werden.<\/p>\n<p>Falls ihr Ritchy bisher noch nicht ausprobiert habt, k\u00f6nnt ihr das gerne tun und im Anschluss die Umfrage ausf\u00fcllen.<\/p>\n<p>Eure Erfahrungen, Ideen und Verbesserungsvorschl\u00e4ge helfen uns, Ritchy gezielt nach euren W\u00fcnschen zu optimieren.<\/p>\n<p>&nbsp;<\/p>\n<h3><span style=\"color: #00549f;\"><strong>Mitmachen lohnt sich! <\/strong><\/span><\/h3>\n<p>Als kleines Dankesch\u00f6n verlosen wir unter allen Teilnehmenden 15 \u201e<a href=\"https:\/\/www.schenk-lokal.de\/stadt-aachen\/\">Schenk Lokal Aachen<\/a>\u201c-Gutscheine im Wert von je 15 Euro. Damit k\u00f6nnt ihr bei zahlreichen Aachener H\u00e4ndlern einkaufen &#8211; eure Meinung zahlt sich direkt aus.<\/p>\n<p>Also: Macht mit, testet Ritchy und teilt uns eure Erfahrungen mit. Jede Stimme z\u00e4hlt!<\/p>\n<p>Jetzt an der <a href=\"https:\/\/www.itc.rwth-aachen.de\/ritchy-umfrage\">Umfrage<\/a> teilnehmen!<\/p>\n<hr \/>\n<p>Verantwortlich f\u00fcr die Inhalte dieses Beitrags ist <a href=\"https:\/\/www.itc.rwth-aachen.de\/go\/id\/epvp\/gguid\/PER-BWYE3CN\/allou\/1\/\">Kyra Heiden<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Seit April 2025 unterst\u00fctzt euch unser Chatbot Ritchy rund um die Uhr &#8211; auch au\u00dferhalb unserer regul\u00e4ren Supportzeiten. Er steht euch mit Antworten, Tipps und L\u00f6sungsvorschl\u00e4gen zur Seite und soll [&hellip;]<\/p>\n","protected":false},"author":1859,"featured_media":22887,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"c2c_always_allow_admin_comments":false,"footnotes":""},"categories":[313],"tags":[1543,112,620,1491,111],"class_list":["post-23291","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-interviews-umfragen","tag-chatbot","tag-feedback","tag-ki","tag-ritchy","tag-umfrage"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.8 - aioseo.com -->\n\t<meta name=\"description\" content=\"Unser Chatbot Ritchy ist rund um die Uhr f\u00fcr euch da. Jetzt brauchen wir eure Meinung! Nehmt an unserer Umfrage teil und helft uns, Ritchy zu verbessern.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Kaminski, Nicole\"\/>\n\t<meta name=\"keywords\" content=\"chatbot,feedback,ki,ritchy,umfrage,interviews &amp; umfragen\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/blog.rwth-aachen.de\/itc\/2025\/11\/24\/ritchy-umfrage\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.8\" \/>\n\t\t<meta property=\"og:locale\" content=\"de_DE\" \/>\n\t\t<meta property=\"og:site_name\" content=\"IT Center Blog \u2022\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Ritchy \u2013 Eure Meinung z\u00e4hlt! \u2022 IT Center Blog\" \/>\n\t\t<meta property=\"og:description\" content=\"Unser Chatbot Ritchy ist rund um die Uhr f\u00fcr euch da. Jetzt brauchen wir eure Meinung! Nehmt an unserer Umfrage teil und helft uns, Ritchy zu verbessern.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/blog.rwth-aachen.de\/itc\/2025\/11\/24\/ritchy-umfrage\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2025-11-24T11:00:37+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-11-21T11:33:17+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/itcenterrwth\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@ITCenterRWTH\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Ritchy \u2013 Eure Meinung z\u00e4hlt! \u2022 IT Center Blog\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Unser Chatbot Ritchy ist rund um die Uhr f\u00fcr euch da. Jetzt brauchen wir eure Meinung! Nehmt an unserer Umfrage teil und helft uns, Ritchy zu verbessern.\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@ITCenterRWTH\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/2025\\\/11\\\/24\\\/ritchy-umfrage\\\/#blogposting\",\"name\":\"Ritchy \\u2013 Eure Meinung z\\u00e4hlt! \\u2022 IT Center Blog\",\"headline\":\"Ritchy \\u2013 Eure Meinung z\\u00e4hlt!\",\"author\":{\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/author\\\/1859\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/files\\\/2025\\\/09\\\/Ritchy_20250919_BAU_Blog.png\",\"width\":1500,\"height\":1000,\"caption\":\"Quelle: Eigene Darstellung\"},\"datePublished\":\"2025-11-24T12:00:37+01:00\",\"dateModified\":\"2025-11-21T12:33:17+01:00\",\"inLanguage\":\"de-DE\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/2025\\\/11\\\/24\\\/ritchy-umfrage\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/2025\\\/11\\\/24\\\/ritchy-umfrage\\\/#webpage\"},\"articleSection\":\"Interviews &amp; Umfragen, Chatbot, Feedback, KI, Ritchy, Umfrage\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/2025\\\/11\\\/24\\\/ritchy-umfrage\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/category\\\/themen\\\/#listItem\",\"name\":\"Themen\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/category\\\/themen\\\/#listItem\",\"position\":2,\"name\":\"Themen\",\"item\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/category\\\/themen\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/category\\\/themen\\\/interviews-umfragen\\\/#listItem\",\"name\":\"Interviews &amp; Umfragen\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/category\\\/themen\\\/interviews-umfragen\\\/#listItem\",\"position\":3,\"name\":\"Interviews &amp; Umfragen\",\"item\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/category\\\/themen\\\/interviews-umfragen\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/2025\\\/11\\\/24\\\/ritchy-umfrage\\\/#listItem\",\"name\":\"Ritchy \\u2013 Eure Meinung z\\u00e4hlt!\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/category\\\/themen\\\/#listItem\",\"name\":\"Themen\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/2025\\\/11\\\/24\\\/ritchy-umfrage\\\/#listItem\",\"position\":4,\"name\":\"Ritchy \\u2013 Eure Meinung z\\u00e4hlt!\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/category\\\/themen\\\/interviews-umfragen\\\/#listItem\",\"name\":\"Interviews &amp; Umfragen\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/#organization\",\"name\":\"IT Center RWTH Aachen University\",\"url\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/files\\\/2018\\\/09\\\/IT-Center-Logo.png\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/2025\\\/11\\\/24\\\/ritchy-umfrage\\\/#organizationLogo\",\"width\":1312,\"height\":378,\"caption\":\"IT Center Logo\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/2025\\\/11\\\/24\\\/ritchy-umfrage\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/itcenterrwth\",\"https:\\\/\\\/twitter.com\\\/ITCenterRWTH\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/itcenterrwthaachen\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/itcenterrwth\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/author\\\/1859\\\/#author\",\"url\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/author\\\/1859\\\/\",\"name\":\"Kaminski, Nicole\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/2025\\\/11\\\/24\\\/ritchy-umfrage\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/18d1e600404bd997e865165f882c6f08cbfabdf461d42cdfbf3619c334f965a4?s=96&d=blank&r=g\",\"width\":96,\"height\":96,\"caption\":\"Kaminski, Nicole\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/2025\\\/11\\\/24\\\/ritchy-umfrage\\\/#webpage\",\"url\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/2025\\\/11\\\/24\\\/ritchy-umfrage\\\/\",\"name\":\"Ritchy \\u2013 Eure Meinung z\\u00e4hlt! \\u2022 IT Center Blog\",\"description\":\"Unser Chatbot Ritchy ist rund um die Uhr f\\u00fcr euch da. Jetzt brauchen wir eure Meinung! Nehmt an unserer Umfrage teil und helft uns, Ritchy zu verbessern.\",\"inLanguage\":\"de-DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/2025\\\/11\\\/24\\\/ritchy-umfrage\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/author\\\/1859\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/author\\\/1859\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/files\\\/2025\\\/09\\\/Ritchy_20250919_BAU_Blog.png\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/2025\\\/11\\\/24\\\/ritchy-umfrage\\\/#mainImage\",\"width\":1500,\"height\":1000,\"caption\":\"Quelle: Eigene Darstellung\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/2025\\\/11\\\/24\\\/ritchy-umfrage\\\/#mainImage\"},\"datePublished\":\"2025-11-24T12:00:37+01:00\",\"dateModified\":\"2025-11-21T12:33:17+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/#website\",\"url\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/\",\"name\":\"IT Center Blog\",\"inLanguage\":\"de-DE\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Ritchy \u2013 Eure Meinung z\u00e4hlt! \u2022 IT Center Blog","description":"Unser Chatbot Ritchy ist rund um die Uhr f\u00fcr euch da. Jetzt brauchen wir eure Meinung! Nehmt an unserer Umfrage teil und helft uns, Ritchy zu verbessern.","canonical_url":"https:\/\/blog.rwth-aachen.de\/itc\/2025\/11\/24\/ritchy-umfrage\/","robots":"max-image-preview:large","keywords":"chatbot,feedback,ki,ritchy,umfrage,interviews &amp; umfragen","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/blog.rwth-aachen.de\/itc\/2025\/11\/24\/ritchy-umfrage\/#blogposting","name":"Ritchy \u2013 Eure Meinung z\u00e4hlt! \u2022 IT Center Blog","headline":"Ritchy \u2013 Eure Meinung z\u00e4hlt!","author":{"@id":"https:\/\/blog.rwth-aachen.de\/itc\/author\/1859\/#author"},"publisher":{"@id":"https:\/\/blog.rwth-aachen.de\/itc\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/blog.rwth-aachen.de\/itc\/files\/2025\/09\/Ritchy_20250919_BAU_Blog.png","width":1500,"height":1000,"caption":"Quelle: Eigene Darstellung"},"datePublished":"2025-11-24T12:00:37+01:00","dateModified":"2025-11-21T12:33:17+01:00","inLanguage":"de-DE","mainEntityOfPage":{"@id":"https:\/\/blog.rwth-aachen.de\/itc\/2025\/11\/24\/ritchy-umfrage\/#webpage"},"isPartOf":{"@id":"https:\/\/blog.rwth-aachen.de\/itc\/2025\/11\/24\/ritchy-umfrage\/#webpage"},"articleSection":"Interviews &amp; Umfragen, Chatbot, Feedback, KI, Ritchy, Umfrage"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.rwth-aachen.de\/itc\/2025\/11\/24\/ritchy-umfrage\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/blog.rwth-aachen.de\/itc#listItem","position":1,"name":"Home","item":"https:\/\/blog.rwth-aachen.de\/itc","nextItem":{"@type":"ListItem","@id":"https:\/\/blog.rwth-aachen.de\/itc\/category\/themen\/#listItem","name":"Themen"}},{"@type":"ListItem","@id":"https:\/\/blog.rwth-aachen.de\/itc\/category\/themen\/#listItem","position":2,"name":"Themen","item":"https:\/\/blog.rwth-aachen.de\/itc\/category\/themen\/","nextItem":{"@type":"ListItem","@id":"https:\/\/blog.rwth-aachen.de\/itc\/category\/themen\/interviews-umfragen\/#listItem","name":"Interviews &amp; Umfragen"},"previousItem":{"@type":"ListItem","@id":"https:\/\/blog.rwth-aachen.de\/itc#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/blog.rwth-aachen.de\/itc\/category\/themen\/interviews-umfragen\/#listItem","position":3,"name":"Interviews &amp; Umfragen","item":"https:\/\/blog.rwth-aachen.de\/itc\/category\/themen\/interviews-umfragen\/","nextItem":{"@type":"ListItem","@id":"https:\/\/blog.rwth-aachen.de\/itc\/2025\/11\/24\/ritchy-umfrage\/#listItem","name":"Ritchy \u2013 Eure Meinung z\u00e4hlt!"},"previousItem":{"@type":"ListItem","@id":"https:\/\/blog.rwth-aachen.de\/itc\/category\/themen\/#listItem","name":"Themen"}},{"@type":"ListItem","@id":"https:\/\/blog.rwth-aachen.de\/itc\/2025\/11\/24\/ritchy-umfrage\/#listItem","position":4,"name":"Ritchy \u2013 Eure Meinung z\u00e4hlt!","previousItem":{"@type":"ListItem","@id":"https:\/\/blog.rwth-aachen.de\/itc\/category\/themen\/interviews-umfragen\/#listItem","name":"Interviews &amp; Umfragen"}}]},{"@type":"Organization","@id":"https:\/\/blog.rwth-aachen.de\/itc\/#organization","name":"IT Center RWTH Aachen University","url":"https:\/\/blog.rwth-aachen.de\/itc\/","logo":{"@type":"ImageObject","url":"https:\/\/blog.rwth-aachen.de\/itc\/files\/2018\/09\/IT-Center-Logo.png","@id":"https:\/\/blog.rwth-aachen.de\/itc\/2025\/11\/24\/ritchy-umfrage\/#organizationLogo","width":1312,"height":378,"caption":"IT Center Logo"},"image":{"@id":"https:\/\/blog.rwth-aachen.de\/itc\/2025\/11\/24\/ritchy-umfrage\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/itcenterrwth","https:\/\/twitter.com\/ITCenterRWTH","https:\/\/www.youtube.com\/c\/itcenterrwthaachen","https:\/\/www.linkedin.com\/company\/itcenterrwth"]},{"@type":"Person","@id":"https:\/\/blog.rwth-aachen.de\/itc\/author\/1859\/#author","url":"https:\/\/blog.rwth-aachen.de\/itc\/author\/1859\/","name":"Kaminski, Nicole","image":{"@type":"ImageObject","@id":"https:\/\/blog.rwth-aachen.de\/itc\/2025\/11\/24\/ritchy-umfrage\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/18d1e600404bd997e865165f882c6f08cbfabdf461d42cdfbf3619c334f965a4?s=96&d=blank&r=g","width":96,"height":96,"caption":"Kaminski, Nicole"}},{"@type":"WebPage","@id":"https:\/\/blog.rwth-aachen.de\/itc\/2025\/11\/24\/ritchy-umfrage\/#webpage","url":"https:\/\/blog.rwth-aachen.de\/itc\/2025\/11\/24\/ritchy-umfrage\/","name":"Ritchy \u2013 Eure Meinung z\u00e4hlt! \u2022 IT Center Blog","description":"Unser Chatbot Ritchy ist rund um die Uhr f\u00fcr euch da. Jetzt brauchen wir eure Meinung! Nehmt an unserer Umfrage teil und helft uns, Ritchy zu verbessern.","inLanguage":"de-DE","isPartOf":{"@id":"https:\/\/blog.rwth-aachen.de\/itc\/#website"},"breadcrumb":{"@id":"https:\/\/blog.rwth-aachen.de\/itc\/2025\/11\/24\/ritchy-umfrage\/#breadcrumblist"},"author":{"@id":"https:\/\/blog.rwth-aachen.de\/itc\/author\/1859\/#author"},"creator":{"@id":"https:\/\/blog.rwth-aachen.de\/itc\/author\/1859\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/blog.rwth-aachen.de\/itc\/files\/2025\/09\/Ritchy_20250919_BAU_Blog.png","@id":"https:\/\/blog.rwth-aachen.de\/itc\/2025\/11\/24\/ritchy-umfrage\/#mainImage","width":1500,"height":1000,"caption":"Quelle: Eigene Darstellung"},"primaryImageOfPage":{"@id":"https:\/\/blog.rwth-aachen.de\/itc\/2025\/11\/24\/ritchy-umfrage\/#mainImage"},"datePublished":"2025-11-24T12:00:37+01:00","dateModified":"2025-11-21T12:33:17+01:00"},{"@type":"WebSite","@id":"https:\/\/blog.rwth-aachen.de\/itc\/#website","url":"https:\/\/blog.rwth-aachen.de\/itc\/","name":"IT Center Blog","inLanguage":"de-DE","publisher":{"@id":"https:\/\/blog.rwth-aachen.de\/itc\/#organization"}}]},"og:locale":"de_DE","og:site_name":"IT Center Blog \u2022","og:type":"article","og:title":"Ritchy \u2013 Eure Meinung z\u00e4hlt! \u2022 IT Center Blog","og:description":"Unser Chatbot Ritchy ist rund um die Uhr f\u00fcr euch da. Jetzt brauchen wir eure Meinung! Nehmt an unserer Umfrage teil und helft uns, Ritchy zu verbessern.","og:url":"https:\/\/blog.rwth-aachen.de\/itc\/2025\/11\/24\/ritchy-umfrage\/","article:published_time":"2025-11-24T11:00:37+00:00","article:modified_time":"2025-11-21T11:33:17+00:00","article:publisher":"https:\/\/www.facebook.com\/itcenterrwth","twitter:card":"summary","twitter:site":"@ITCenterRWTH","twitter:title":"Ritchy \u2013 Eure Meinung z\u00e4hlt! \u2022 IT Center Blog","twitter:description":"Unser Chatbot Ritchy ist rund um die Uhr f\u00fcr euch da. Jetzt brauchen wir eure Meinung! Nehmt an unserer Umfrage teil und helft uns, Ritchy zu verbessern.","twitter:creator":"@ITCenterRWTH"},"aioseo_meta_data":{"post_id":"23291","title":null,"description":"Unser Chatbot Ritchy ist rund um die Uhr f\u00fcr euch da. Jetzt brauchen wir eure Meinung! Nehmt an unserer Umfrage teil und helft uns, Ritchy zu verbessern.","keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2025-11-18 11:36:00","updated":"2025-11-24 11:09:04","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/blog.rwth-aachen.de\/itc\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/blog.rwth-aachen.de\/itc\/category\/themen\/\" title=\"Themen\">Themen<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/blog.rwth-aachen.de\/itc\/category\/themen\/interviews-umfragen\/\" title=\"Interviews &amp; Umfragen\">Interviews &amp; Umfragen<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tRitchy \u2013 Eure Meinung z\u00e4hlt!\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/blog.rwth-aachen.de\/itc"},{"label":"Themen","link":"https:\/\/blog.rwth-aachen.de\/itc\/category\/themen\/"},{"label":"Interviews &amp; Umfragen","link":"https:\/\/blog.rwth-aachen.de\/itc\/category\/themen\/interviews-umfragen\/"},{"label":"Ritchy \u2013 Eure Meinung z\u00e4hlt!","link":"https:\/\/blog.rwth-aachen.de\/itc\/2025\/11\/24\/ritchy-umfrage\/"}],"_links":{"self":[{"href":"https:\/\/blog.rwth-aachen.de\/itc\/wp-json\/wp\/v2\/posts\/23291","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.rwth-aachen.de\/itc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.rwth-aachen.de\/itc\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.rwth-aachen.de\/itc\/wp-json\/wp\/v2\/users\/1859"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.rwth-aachen.de\/itc\/wp-json\/wp\/v2\/comments?post=23291"}],"version-history":[{"count":3,"href":"https:\/\/blog.rwth-aachen.de\/itc\/wp-json\/wp\/v2\/posts\/23291\/revisions"}],"predecessor-version":[{"id":23297,"href":"https:\/\/blog.rwth-aachen.de\/itc\/wp-json\/wp\/v2\/posts\/23291\/revisions\/23297"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.rwth-aachen.de\/itc\/wp-json\/wp\/v2\/media\/22887"}],"wp:attachment":[{"href":"https:\/\/blog.rwth-aachen.de\/itc\/wp-json\/wp\/v2\/media?parent=23291"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.rwth-aachen.de\/itc\/wp-json\/wp\/v2\/categories?post=23291"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.rwth-aachen.de\/itc\/wp-json\/wp\/v2\/tags?post=23291"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}