{"id":7037,"date":"2020-02-28T13:00:05","date_gmt":"2020-02-28T12:00:05","guid":{"rendered":"https:\/\/blog.rwth-aachen.de\/itc\/?p=7037"},"modified":"2023-07-24T11:18:08","modified_gmt":"2023-07-24T09:18:08","slug":"abschaltung-tls-supportende-win7","status":"publish","type":"post","link":"https:\/\/blog.rwth-aachen.de\/itc\/2020\/02\/28\/abschaltung-tls-supportende-win7\/","title":{"rendered":"Abschaltung von TLS 1.0 und TLS 1.1 sowie Supportende f\u00fcr Windows 7"},"content":{"rendered":"<div class=\"twoclick_social_bookmarks_post_7037 social_share_privacy clearfix 1.6.4 locale-de_DE sprite-de_DE\"><\/div><div class=\"twoclick-js\"><script type=\"text\/javascript\">\/* <![CDATA[ *\/\njQuery(document).ready(function($){if($('.twoclick_social_bookmarks_post_7037')){$('.twoclick_social_bookmarks_post_7037').socialSharePrivacy({\"txt_help\":\"Wenn Sie diese Felder durch einen Klick aktivieren, werden Informationen an Facebook, Twitter, Flattr, Xing, t3n, LinkedIn, Pinterest oder Google eventuell ins Ausland \\u00fcbertragen und unter Umst\\u00e4nden auch dort gespeichert. N\\u00e4heres erfahren Sie durch einen Klick auf das <em>i<\\\/em>.\",\"settings_perma\":\"Dauerhaft aktivieren und Daten\\u00fcber-tragung zustimmen:\",\"info_link\":\"http:\\\/\\\/www.heise.de\\\/ct\\\/artikel\\\/2-Klicks-fuer-mehr-Datenschutz-1333879.html\",\"uri\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/2020\\\/02\\\/28\\\/abschaltung-tls-supportende-win7\\\/\",\"post_id\":7037,\"post_title_referrer_track\":\"Abschaltung+von+TLS+1.0+und+TLS+1.1+sowie+Supportende+f%C3%BCr+Windows+7\",\"display_infobox\":\"on\"});}});\n\/* ]]> *\/<\/script><\/div>\r\n<p>&nbsp;<\/p>\r\n\r\n<h3 class=\"wp-block-heading\">Kein Zugriff mehr auf den RWTH E-Mail Service? Woran liegt das?<\/h3>\r\n\r\n<p>&nbsp;<\/p>\r\n\r\n<p class=\"wp-block-paragraph\">Anfang 2020 beschlossen die Browserhersteller Mozilla, Google und Microsoft die Verschl\u00fcsselungsprotokolle TLS 1.0 sowie TLS 1.1 nicht mehr zu unterst\u00fctzen. Diese Protokolle gelten inzwischen als unsicher und enthalten bekannte Sicherheitsl\u00fccken. In diesem Zusammenhang hat das <a href=\"https:\/\/www.itc.rwth-aachen.de\/cms\/~rbnjb\/it-center\/lidx\/1\/\">IT Center<\/a> beschlossen, diese beide Protokolle ebenfalls f\u00fcr den <a href=\"https:\/\/www.itc.rwth-aachen.de\/cms\/IT-Center\/Services\/kompletter-Servicekatalog\/Anwendungen-und-Prozessunterstuetzung\/~essy\/E-Mail\/\">RWTH-Service \u201eE-Mail<\/a>&#8220; abzuschalten. Diese werden seit dem 13.01.2020 durch das Protokoll TLS 1.2 ersetzt.<\/p>\r\n\r\n<p>&nbsp;<\/p>\r\n\r\n<figure class=\"wp-block-image\">\r\n<div id=\"attachment_7038\" style=\"width: 1034px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-7038\" class=\"wp-image-7038\" src=\"https:\/\/blog.rwth-aachen.de\/itc\/files\/2020\/02\/TLS_Security-1024x683.jpg\" alt=\"\" width=\"1024\" height=\"683\" srcset=\"https:\/\/blog.rwth-aachen.de\/itc\/files\/2020\/02\/TLS_Security-1024x683.jpg 1024w, https:\/\/blog.rwth-aachen.de\/itc\/files\/2020\/02\/TLS_Security-300x200.jpg 300w, https:\/\/blog.rwth-aachen.de\/itc\/files\/2020\/02\/TLS_Security-768x512.jpg 768w, https:\/\/blog.rwth-aachen.de\/itc\/files\/2020\/02\/TLS_Security.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><p id=\"caption-attachment-7038\" class=\"wp-caption-text\">Safety first! Sicherheit auf Deinen Ger\u00e4ten hat oberste Priorit\u00e4t. <br \/>Quelle: <a href=\" https:\/\/pixabay.com\/de\/photos\/sicherheit-schutz-antivirus-265130\/\">Pixabay<\/a><\/p><\/div>\r\n\r\n<\/figure>\r\n\r\n\r\n\r\n<p><!--more--><\/p>\r\n\r\n<p>&nbsp;<\/p>\r\n\r\n<p class=\"wp-block-paragraph\">Durch diese Ma\u00dfnahme k\u00f6nnen folgende Systeme keine Verbindung mehr zum zentralen Mailsystem der RWTH aufbauen:<\/p>\r\n\r\n<p>&nbsp;<\/p>\r\n\r\n<ul class=\"wp-block-list\">\r\n<li>Android 4.3 und \u00e4lter<\/li>\r\n<li>Internet Explorer 7-10 unter Windows Vista\/Windows 7<\/li>\r\n<li>Safari 5.1.9 und Safari 6.0.4 unter OS X 10.6.8 und OS X 10.8.4<\/li>\r\n<\/ul>\r\n\r\n<p>&nbsp;<\/p>\r\n\r\n<p class=\"wp-block-paragraph\">Zus\u00e4tzlich wurden die folgenden Chiffrensammlungen \u2013sogenannte Cipher Suits, ebenfalls abgeschaltet, da diese als zu schwach gelten:<\/p>\r\n\r\n<p>&nbsp;<\/p>\r\n\r\n<ul class=\"wp-block-list\">\r\n<li>TLS_ECDHE_RSA_WITH_AES_256_CBC_SHA<\/li>\r\n<li>TLS_ECDHE_RSA_WITH_AES_256_CBC_SHA384<\/li>\r\n<li>TLS_ECDHE_RSA_WITH_AES_128_CBC_SHA<\/li>\r\n<li>TLS_ECDHE_RSA_WITH_AES_128_CBC_SHA256<\/li>\r\n<\/ul>\r\n\r\n<p>&nbsp;<\/p>\r\n\r\n<p class=\"wp-block-paragraph\">Die Abschaltung der Verschl\u00fcsselungsprotokolle TLS 1.0 und TLS 1.1 f\u00e4llt mit dem Ende des Supports f\u00fcr Windows 7 zusammen. Dadurch k\u00f6nnen ebenfalls Probleme entstehen, beispielsweise bei der Nutzung von Clients wie Outlook. Das liegt daran, dass TLS 1.2 im WinHTTP-Subsystem von Windows 7, das von Outlook f\u00fcr Proxy-Server gebraucht wird, nicht aktiviert ist.<\/p>\r\n\r\n<p>&nbsp;<\/p>\r\n\r\n<h3 class=\"wp-block-heading\">So behebt Ihr das Problem<\/h3>\r\n\r\n<p>&nbsp;<\/p>\r\n\r\n<p class=\"wp-block-paragraph\">Solltet Ihr also keinen Zugriff mehr auf Eure RWTH-E-Mails haben, empfehlen wir Euch die Versionen Eurer Browser und Betriebssysteme zu aktualisieren. Ein Upgrade von Windows 7 auf Windows 10 wird hier dringend empfohlen. Falls Ihr Windows 7 benutzt und ein Upgrade auf Windows 10 nicht m\u00f6glich ist, findet Ihr auf der Microsoft Support Webseite eine <a href=\"https:\/\/support.microsoft.com\/de-de\/help\/3140245\/update-to-enable-tls-1-1-and-tls-1-2-as-default-secure-protocols-in-wi\">Anleitung<\/a> zur Behebung des Problems. Andernfalls ist Euer Rechner oder Ger\u00e4t nicht mehr ausreichend gesch\u00fctzt.<\/p>\r\n\r\n<p>&nbsp;<\/p>\r\n\r\n<p class=\"wp-block-paragraph\">Bei allen Rechnern und Ger\u00e4ten der verschiedenen Institute der RWTH ist dieses Upgrade zu Windows 10 allerdings unabdinglich, da die Sicherheit von den Instituten gew\u00e4hrleistet werden muss. Bei eventuellen Problemen oder Fragen bez\u00fcglich dieses Upgrades innerhalb der Institute solltet Ihr Euch an den lokalen Administrator innerhalb des Institutes wenden.<\/p>\r\n\r\n<p>&nbsp;<\/p>\r\n\r\n<p class=\"wp-block-paragraph\">Verantwortlich f\u00fcr die Inhalte dieses Beitrags ist <a href=\"https:\/\/www.itc.rwth-aachen.de\/cms\/IT-Center\/IT-Center\/Team\/~epvp\/Mitarbeiter-CAMPUS-\/?gguid=0x2C5E1B0A3DA32A45AB293A42E93EEC07&amp;allou=1\">St\u00e9phanie Bauens<\/a>.<\/p>\r\n\r\n<p>&nbsp;<\/p>\r\n\r\n<p>&nbsp;<\/p>\r\n\r\n<p>&nbsp;<\/p>\r\n\r\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>&nbsp; Kein Zugriff mehr auf den RWTH E-Mail Service? Woran liegt das? &nbsp; Anfang 2020 beschlossen die Browserhersteller Mozilla, Google und Microsoft die Verschl\u00fcsselungsprotokolle TLS 1.0 sowie TLS 1.1 nicht [&hellip;]<\/p>\n","protected":false},"author":1413,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"c2c_always_allow_admin_comments":false,"footnotes":""},"categories":[315],"tags":[],"class_list":["post-7037","post","type-post","status-publish","format-standard","hentry","category-services-support"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.8 - aioseo.com -->\n\t<meta name=\"description\" content=\"Kein Zugriff mehr auf den RWTH E-Mail Service? Woran liegt das? Anfang 2020 beschlossen die Browserhersteller Mozilla, Google und Microsoft die Verschl\u00fcsselungsprotokolle TLS 1.0 sowie TLS 1.1 nicht mehr zu unterst\u00fctzen. Diese Protokolle gelten inzwischen als unsicher und enthalten bekannte Sicherheitsl\u00fccken. In diesem Zusammenhang hat das IT Center beschlossen, diese beide Protokolle ebenfalls\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Filla, Nicole Barbara\"\/>\n\t<meta name=\"keywords\" content=\"services &amp; support\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/blog.rwth-aachen.de\/itc\/2020\/02\/28\/abschaltung-tls-supportende-win7\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.8\" \/>\n\t\t<meta property=\"og:locale\" content=\"de_DE\" \/>\n\t\t<meta property=\"og:site_name\" content=\"IT Center Blog \u2022\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Abschaltung von TLS 1.0 und TLS 1.1 sowie Supportende f\u00fcr Windows 7 \u2022 IT Center Blog\" \/>\n\t\t<meta property=\"og:description\" content=\"Kein Zugriff mehr auf den RWTH E-Mail Service? Woran liegt das? Anfang 2020 beschlossen die Browserhersteller Mozilla, Google und Microsoft die Verschl\u00fcsselungsprotokolle TLS 1.0 sowie TLS 1.1 nicht mehr zu unterst\u00fctzen. Diese Protokolle gelten inzwischen als unsicher und enthalten bekannte Sicherheitsl\u00fccken. In diesem Zusammenhang hat das IT Center beschlossen, diese beide Protokolle ebenfalls\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/blog.rwth-aachen.de\/itc\/2020\/02\/28\/abschaltung-tls-supportende-win7\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2020-02-28T12:00:05+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-07-24T09:18:08+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/itcenterrwth\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@ITCenterRWTH\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Abschaltung von TLS 1.0 und TLS 1.1 sowie Supportende f\u00fcr Windows 7 \u2022 IT Center Blog\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Kein Zugriff mehr auf den RWTH E-Mail Service? Woran liegt das? Anfang 2020 beschlossen die Browserhersteller Mozilla, Google und Microsoft die Verschl\u00fcsselungsprotokolle TLS 1.0 sowie TLS 1.1 nicht mehr zu unterst\u00fctzen. Diese Protokolle gelten inzwischen als unsicher und enthalten bekannte Sicherheitsl\u00fccken. In diesem Zusammenhang hat das IT Center beschlossen, diese beide Protokolle ebenfalls\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@ITCenterRWTH\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/2020\\\/02\\\/28\\\/abschaltung-tls-supportende-win7\\\/#blogposting\",\"name\":\"Abschaltung von TLS 1.0 und TLS 1.1 sowie Supportende f\\u00fcr Windows 7 \\u2022 IT Center Blog\",\"headline\":\"Abschaltung von TLS 1.0 und TLS 1.1 sowie Supportende f\\u00fcr Windows 7\",\"author\":{\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/author\\\/1413\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/files\\\/2020\\\/02\\\/TLS_Security.jpg\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/2020\\\/02\\\/28\\\/abschaltung-tls-supportende-win7\\\/#articleImage\",\"width\":1920,\"height\":1280,\"caption\":\"Safety first! Sicherheit auf Deinen Ger\\u00e4ten hat oberste Priorit\\u00e4t.\"},\"datePublished\":\"2020-02-28T13:00:05+01:00\",\"dateModified\":\"2023-07-24T11:18:08+02:00\",\"inLanguage\":\"de-DE\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/2020\\\/02\\\/28\\\/abschaltung-tls-supportende-win7\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/2020\\\/02\\\/28\\\/abschaltung-tls-supportende-win7\\\/#webpage\"},\"articleSection\":\"Services &amp; Support\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/2020\\\/02\\\/28\\\/abschaltung-tls-supportende-win7\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/category\\\/themen\\\/#listItem\",\"name\":\"Themen\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/category\\\/themen\\\/#listItem\",\"position\":2,\"name\":\"Themen\",\"item\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/category\\\/themen\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/category\\\/themen\\\/services-support\\\/#listItem\",\"name\":\"Services &amp; Support\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/category\\\/themen\\\/services-support\\\/#listItem\",\"position\":3,\"name\":\"Services &amp; Support\",\"item\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/category\\\/themen\\\/services-support\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/2020\\\/02\\\/28\\\/abschaltung-tls-supportende-win7\\\/#listItem\",\"name\":\"Abschaltung von TLS 1.0 und TLS 1.1 sowie Supportende f\\u00fcr Windows 7\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/category\\\/themen\\\/#listItem\",\"name\":\"Themen\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/2020\\\/02\\\/28\\\/abschaltung-tls-supportende-win7\\\/#listItem\",\"position\":4,\"name\":\"Abschaltung von TLS 1.0 und TLS 1.1 sowie Supportende f\\u00fcr Windows 7\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/category\\\/themen\\\/services-support\\\/#listItem\",\"name\":\"Services &amp; Support\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/#organization\",\"name\":\"IT Center RWTH Aachen University\",\"url\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/files\\\/2018\\\/09\\\/IT-Center-Logo.png\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/2020\\\/02\\\/28\\\/abschaltung-tls-supportende-win7\\\/#organizationLogo\",\"width\":1312,\"height\":378,\"caption\":\"IT Center Logo\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/2020\\\/02\\\/28\\\/abschaltung-tls-supportende-win7\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/itcenterrwth\",\"https:\\\/\\\/twitter.com\\\/ITCenterRWTH\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/itcenterrwthaachen\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/itcenterrwth\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/author\\\/1413\\\/#author\",\"url\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/author\\\/1413\\\/\",\"name\":\"Filla, Nicole Barbara\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/2020\\\/02\\\/28\\\/abschaltung-tls-supportende-win7\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/81792330c0dc846cc349c48b76b9d81506aee430174a58d2e4bfac4514336eb4?s=96&d=blank&r=g\",\"width\":96,\"height\":96,\"caption\":\"Filla, Nicole Barbara\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/2020\\\/02\\\/28\\\/abschaltung-tls-supportende-win7\\\/#webpage\",\"url\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/2020\\\/02\\\/28\\\/abschaltung-tls-supportende-win7\\\/\",\"name\":\"Abschaltung von TLS 1.0 und TLS 1.1 sowie Supportende f\\u00fcr Windows 7 \\u2022 IT Center Blog\",\"description\":\"Kein Zugriff mehr auf den RWTH E-Mail Service? Woran liegt das? Anfang 2020 beschlossen die Browserhersteller Mozilla, Google und Microsoft die Verschl\\u00fcsselungsprotokolle TLS 1.0 sowie TLS 1.1 nicht mehr zu unterst\\u00fctzen. Diese Protokolle gelten inzwischen als unsicher und enthalten bekannte Sicherheitsl\\u00fccken. In diesem Zusammenhang hat das IT Center beschlossen, diese beide Protokolle ebenfalls\",\"inLanguage\":\"de-DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/2020\\\/02\\\/28\\\/abschaltung-tls-supportende-win7\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/author\\\/1413\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/author\\\/1413\\\/#author\"},\"datePublished\":\"2020-02-28T13:00:05+01:00\",\"dateModified\":\"2023-07-24T11:18:08+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/#website\",\"url\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/\",\"name\":\"IT Center Blog\",\"inLanguage\":\"de-DE\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.rwth-aachen.de\\\/itc\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Abschaltung von TLS 1.0 und TLS 1.1 sowie Supportende f\u00fcr Windows 7 \u2022 IT Center Blog","description":"Kein Zugriff mehr auf den RWTH E-Mail Service? Woran liegt das? Anfang 2020 beschlossen die Browserhersteller Mozilla, Google und Microsoft die Verschl\u00fcsselungsprotokolle TLS 1.0 sowie TLS 1.1 nicht mehr zu unterst\u00fctzen. Diese Protokolle gelten inzwischen als unsicher und enthalten bekannte Sicherheitsl\u00fccken. In diesem Zusammenhang hat das IT Center beschlossen, diese beide Protokolle ebenfalls","canonical_url":"https:\/\/blog.rwth-aachen.de\/itc\/2020\/02\/28\/abschaltung-tls-supportende-win7\/","robots":"max-image-preview:large","keywords":"services &amp; support","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/blog.rwth-aachen.de\/itc\/2020\/02\/28\/abschaltung-tls-supportende-win7\/#blogposting","name":"Abschaltung von TLS 1.0 und TLS 1.1 sowie Supportende f\u00fcr Windows 7 \u2022 IT Center Blog","headline":"Abschaltung von TLS 1.0 und TLS 1.1 sowie Supportende f\u00fcr Windows 7","author":{"@id":"https:\/\/blog.rwth-aachen.de\/itc\/author\/1413\/#author"},"publisher":{"@id":"https:\/\/blog.rwth-aachen.de\/itc\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/blog.rwth-aachen.de\/itc\/files\/2020\/02\/TLS_Security.jpg","@id":"https:\/\/blog.rwth-aachen.de\/itc\/2020\/02\/28\/abschaltung-tls-supportende-win7\/#articleImage","width":1920,"height":1280,"caption":"Safety first! Sicherheit auf Deinen Ger\u00e4ten hat oberste Priorit\u00e4t."},"datePublished":"2020-02-28T13:00:05+01:00","dateModified":"2023-07-24T11:18:08+02:00","inLanguage":"de-DE","mainEntityOfPage":{"@id":"https:\/\/blog.rwth-aachen.de\/itc\/2020\/02\/28\/abschaltung-tls-supportende-win7\/#webpage"},"isPartOf":{"@id":"https:\/\/blog.rwth-aachen.de\/itc\/2020\/02\/28\/abschaltung-tls-supportende-win7\/#webpage"},"articleSection":"Services &amp; Support"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.rwth-aachen.de\/itc\/2020\/02\/28\/abschaltung-tls-supportende-win7\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/blog.rwth-aachen.de\/itc#listItem","position":1,"name":"Home","item":"https:\/\/blog.rwth-aachen.de\/itc","nextItem":{"@type":"ListItem","@id":"https:\/\/blog.rwth-aachen.de\/itc\/category\/themen\/#listItem","name":"Themen"}},{"@type":"ListItem","@id":"https:\/\/blog.rwth-aachen.de\/itc\/category\/themen\/#listItem","position":2,"name":"Themen","item":"https:\/\/blog.rwth-aachen.de\/itc\/category\/themen\/","nextItem":{"@type":"ListItem","@id":"https:\/\/blog.rwth-aachen.de\/itc\/category\/themen\/services-support\/#listItem","name":"Services &amp; Support"},"previousItem":{"@type":"ListItem","@id":"https:\/\/blog.rwth-aachen.de\/itc#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/blog.rwth-aachen.de\/itc\/category\/themen\/services-support\/#listItem","position":3,"name":"Services &amp; Support","item":"https:\/\/blog.rwth-aachen.de\/itc\/category\/themen\/services-support\/","nextItem":{"@type":"ListItem","@id":"https:\/\/blog.rwth-aachen.de\/itc\/2020\/02\/28\/abschaltung-tls-supportende-win7\/#listItem","name":"Abschaltung von TLS 1.0 und TLS 1.1 sowie Supportende f\u00fcr Windows 7"},"previousItem":{"@type":"ListItem","@id":"https:\/\/blog.rwth-aachen.de\/itc\/category\/themen\/#listItem","name":"Themen"}},{"@type":"ListItem","@id":"https:\/\/blog.rwth-aachen.de\/itc\/2020\/02\/28\/abschaltung-tls-supportende-win7\/#listItem","position":4,"name":"Abschaltung von TLS 1.0 und TLS 1.1 sowie Supportende f\u00fcr Windows 7","previousItem":{"@type":"ListItem","@id":"https:\/\/blog.rwth-aachen.de\/itc\/category\/themen\/services-support\/#listItem","name":"Services &amp; Support"}}]},{"@type":"Organization","@id":"https:\/\/blog.rwth-aachen.de\/itc\/#organization","name":"IT Center RWTH Aachen University","url":"https:\/\/blog.rwth-aachen.de\/itc\/","logo":{"@type":"ImageObject","url":"https:\/\/blog.rwth-aachen.de\/itc\/files\/2018\/09\/IT-Center-Logo.png","@id":"https:\/\/blog.rwth-aachen.de\/itc\/2020\/02\/28\/abschaltung-tls-supportende-win7\/#organizationLogo","width":1312,"height":378,"caption":"IT Center Logo"},"image":{"@id":"https:\/\/blog.rwth-aachen.de\/itc\/2020\/02\/28\/abschaltung-tls-supportende-win7\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/itcenterrwth","https:\/\/twitter.com\/ITCenterRWTH","https:\/\/www.youtube.com\/c\/itcenterrwthaachen","https:\/\/www.linkedin.com\/company\/itcenterrwth"]},{"@type":"Person","@id":"https:\/\/blog.rwth-aachen.de\/itc\/author\/1413\/#author","url":"https:\/\/blog.rwth-aachen.de\/itc\/author\/1413\/","name":"Filla, Nicole Barbara","image":{"@type":"ImageObject","@id":"https:\/\/blog.rwth-aachen.de\/itc\/2020\/02\/28\/abschaltung-tls-supportende-win7\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/81792330c0dc846cc349c48b76b9d81506aee430174a58d2e4bfac4514336eb4?s=96&d=blank&r=g","width":96,"height":96,"caption":"Filla, Nicole Barbara"}},{"@type":"WebPage","@id":"https:\/\/blog.rwth-aachen.de\/itc\/2020\/02\/28\/abschaltung-tls-supportende-win7\/#webpage","url":"https:\/\/blog.rwth-aachen.de\/itc\/2020\/02\/28\/abschaltung-tls-supportende-win7\/","name":"Abschaltung von TLS 1.0 und TLS 1.1 sowie Supportende f\u00fcr Windows 7 \u2022 IT Center Blog","description":"Kein Zugriff mehr auf den RWTH E-Mail Service? Woran liegt das? Anfang 2020 beschlossen die Browserhersteller Mozilla, Google und Microsoft die Verschl\u00fcsselungsprotokolle TLS 1.0 sowie TLS 1.1 nicht mehr zu unterst\u00fctzen. Diese Protokolle gelten inzwischen als unsicher und enthalten bekannte Sicherheitsl\u00fccken. In diesem Zusammenhang hat das IT Center beschlossen, diese beide Protokolle ebenfalls","inLanguage":"de-DE","isPartOf":{"@id":"https:\/\/blog.rwth-aachen.de\/itc\/#website"},"breadcrumb":{"@id":"https:\/\/blog.rwth-aachen.de\/itc\/2020\/02\/28\/abschaltung-tls-supportende-win7\/#breadcrumblist"},"author":{"@id":"https:\/\/blog.rwth-aachen.de\/itc\/author\/1413\/#author"},"creator":{"@id":"https:\/\/blog.rwth-aachen.de\/itc\/author\/1413\/#author"},"datePublished":"2020-02-28T13:00:05+01:00","dateModified":"2023-07-24T11:18:08+02:00"},{"@type":"WebSite","@id":"https:\/\/blog.rwth-aachen.de\/itc\/#website","url":"https:\/\/blog.rwth-aachen.de\/itc\/","name":"IT Center Blog","inLanguage":"de-DE","publisher":{"@id":"https:\/\/blog.rwth-aachen.de\/itc\/#organization"}}]},"og:locale":"de_DE","og:site_name":"IT Center Blog \u2022","og:type":"article","og:title":"Abschaltung von TLS 1.0 und TLS 1.1 sowie Supportende f\u00fcr Windows 7 \u2022 IT Center Blog","og:description":"Kein Zugriff mehr auf den RWTH E-Mail Service? Woran liegt das? Anfang 2020 beschlossen die Browserhersteller Mozilla, Google und Microsoft die Verschl\u00fcsselungsprotokolle TLS 1.0 sowie TLS 1.1 nicht mehr zu unterst\u00fctzen. Diese Protokolle gelten inzwischen als unsicher und enthalten bekannte Sicherheitsl\u00fccken. In diesem Zusammenhang hat das IT Center beschlossen, diese beide Protokolle ebenfalls","og:url":"https:\/\/blog.rwth-aachen.de\/itc\/2020\/02\/28\/abschaltung-tls-supportende-win7\/","article:published_time":"2020-02-28T12:00:05+00:00","article:modified_time":"2023-07-24T09:18:08+00:00","article:publisher":"https:\/\/www.facebook.com\/itcenterrwth","twitter:card":"summary","twitter:site":"@ITCenterRWTH","twitter:title":"Abschaltung von TLS 1.0 und TLS 1.1 sowie Supportende f\u00fcr Windows 7 \u2022 IT Center Blog","twitter:description":"Kein Zugriff mehr auf den RWTH E-Mail Service? Woran liegt das? Anfang 2020 beschlossen die Browserhersteller Mozilla, Google und Microsoft die Verschl\u00fcsselungsprotokolle TLS 1.0 sowie TLS 1.1 nicht mehr zu unterst\u00fctzen. Diese Protokolle gelten inzwischen als unsicher und enthalten bekannte Sicherheitsl\u00fccken. In diesem Zusammenhang hat das IT Center beschlossen, diese beide Protokolle ebenfalls","twitter:creator":"@ITCenterRWTH"},"aioseo_meta_data":{"post_id":"7037","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2022-01-24 14:45:04","updated":"2025-07-08 13:33:34","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/blog.rwth-aachen.de\/itc\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/blog.rwth-aachen.de\/itc\/category\/themen\/\" title=\"Themen\">Themen<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/blog.rwth-aachen.de\/itc\/category\/themen\/services-support\/\" title=\"Services &amp; Support\">Services &amp; Support<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tAbschaltung von TLS 1.0 und TLS 1.1 sowie Supportende f\u00fcr Windows 7\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/blog.rwth-aachen.de\/itc"},{"label":"Themen","link":"https:\/\/blog.rwth-aachen.de\/itc\/category\/themen\/"},{"label":"Services &amp; Support","link":"https:\/\/blog.rwth-aachen.de\/itc\/category\/themen\/services-support\/"},{"label":"Abschaltung von TLS 1.0 und TLS 1.1 sowie Supportende f\u00fcr Windows 7","link":"https:\/\/blog.rwth-aachen.de\/itc\/2020\/02\/28\/abschaltung-tls-supportende-win7\/"}],"_links":{"self":[{"href":"https:\/\/blog.rwth-aachen.de\/itc\/wp-json\/wp\/v2\/posts\/7037","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.rwth-aachen.de\/itc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.rwth-aachen.de\/itc\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.rwth-aachen.de\/itc\/wp-json\/wp\/v2\/users\/1413"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.rwth-aachen.de\/itc\/wp-json\/wp\/v2\/comments?post=7037"}],"version-history":[{"count":13,"href":"https:\/\/blog.rwth-aachen.de\/itc\/wp-json\/wp\/v2\/posts\/7037\/revisions"}],"predecessor-version":[{"id":16492,"href":"https:\/\/blog.rwth-aachen.de\/itc\/wp-json\/wp\/v2\/posts\/7037\/revisions\/16492"}],"wp:attachment":[{"href":"https:\/\/blog.rwth-aachen.de\/itc\/wp-json\/wp\/v2\/media?parent=7037"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.rwth-aachen.de\/itc\/wp-json\/wp\/v2\/categories?post=7037"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.rwth-aachen.de\/itc\/wp-json\/wp\/v2\/tags?post=7037"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}